{"id":8166400,"date":"2025-10-01T16:36:58","date_gmt":"2025-10-01T14:36:58","guid":{"rendered":"https:\/\/www.wildix.com\/wildix-recognized-in-2025-gartner-magic-quadrant-for-unified-communications-as-a-service\/"},"modified":"2025-10-07T18:29:09","modified_gmt":"2025-10-07T16:29:09","slug":"wildix-riconosciuta-nel-gartner-magic-quadrant-2025-per-unified-communications-as-a-service-ucaas","status":"publish","type":"post","link":"https:\/\/www.wildix.com\/it\/wildix-riconosciuta-nel-gartner-magic-quadrant-2025-per-unified-communications-as-a-service-ucaas\/","title":{"rendered":"Wildix riconosciuta nel\u00a0Gartner\u00ae Magic\u00a0Quadrant\u2122\u00a02025 per Unified Communications as\u00a0a\u00a0Service\u00a0(UCaaS)"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"8166400\" class=\"elementor elementor-8166400 elementor-8166047\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0aac972 e-con-full e-flex e-con e-child\" data-id=\"0aac972\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a642743 elementor-widget elementor-widget-text-editor\" data-id=\"a642743\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<span style=\"background-color: #003366; color: #ffffff; padding: 10px 10px 10px 10px; border-radius: 3px;\">Comunicato stampa\n<\/span>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0bb3a36 elementor-widget elementor-widget-heading\" data-id=\"0bb3a36\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Quinto anno consecutivo di\u00a0riconoscimento; ha\u00a0avanzato nella \"Completeness of\u00a0Vision\" rispetto al\u00a0posizionamento del\u00a02024<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1f0a12f e-con-full e-flex e-con e-child\" data-id=\"1f0a12f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t<div class=\"elementor-element elementor-element-5af69e9 e-con-full e-flex e-con e-child\" data-id=\"5af69e9\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-34a12ee elementor-widget elementor-widget-text-editor\" data-id=\"34a12ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<b>Tallinn, Estonia\u00a0\u2014 30\u00a0settembre\u00a02025<\/b>\u00a0\u2014 Wildix, fornitore globale di soluzioni di comunicazione aziendale basate sull&#8217;intelligenza artificiale, ha annunciato oggi di essere stata riconosciuta come Niche Player nel Gartner\u00ae Magic Quadrant\u2122 2025 per Unified Communications as\u00a0a\u00a0Service (UCaaS).\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9c521ed elementor-widget elementor-widget-text-editor\" data-id=\"9c521ed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\u00c8 il quinto anno consecutivo che Wildix \u00e8\u00a0inclusa nel\u00a0report, rimanendo l&#8217;unico vendor europeo\u00a0riconosciuto.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ac2a518 e-con-full e-flex e-con e-child\" data-id=\"ac2a518\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-41ebadb elementor-widget elementor-widget-image\" data-id=\"41ebadb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1200\" height=\"630\" src=\"https:\/\/www.wildix.com\/wp-content\/uploads\/2025\/10\/Wildix-Gartner-Magic-Quadrant-2025-PR-IT.webp\" class=\"attachment-full size-full wp-image-8166623\" alt=\"Wildix Gartner Magic Quadrant 2025 PR IT\" srcset=\"https:\/\/www.wildix.com\/wp-content\/uploads\/2025\/10\/Wildix-Gartner-Magic-Quadrant-2025-PR-IT.webp 1200w, https:\/\/www.wildix.com\/wp-content\/uploads\/2025\/10\/Wildix-Gartner-Magic-Quadrant-2025-PR-IT-300x158.webp 300w, https:\/\/www.wildix.com\/wp-content\/uploads\/2025\/10\/Wildix-Gartner-Magic-Quadrant-2025-PR-IT-1024x538.webp 1024w, https:\/\/www.wildix.com\/wp-content\/uploads\/2025\/10\/Wildix-Gartner-Magic-Quadrant-2025-PR-IT-768x403.webp 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b61fc6b elementor-widget elementor-widget-text-editor\" data-id=\"b61fc6b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tNell\u2019edizione 2025, Wildix ha inoltre avanzato ulteriormente sull&#8217;asse della &#8220;Completeness of Vision&#8221; all&#8217;interno del quadrante dei\u00a0Niche Players, migliorando la\u00a0propria posizione rispetto al\u00a02024.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-21e7b8c elementor-widget elementor-widget-text-editor\" data-id=\"21e7b8c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tIl modello Wildix si distingue per l&#8217;attenzione rivolta alle medie imprese, alle organizzazioni orientate alle vendite e ai settori con una forte presenza di personale operativo. Con una solida base in Europa e una crescita costante in Nord America, l&#8217;azienda continua a rafforzare la\u00a0propria presenza\u00a0globale.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ec58703 testimonials-block elementor-widget elementor-widget-testimonial\" data-id=\"ec58703\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"testimonial.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial-wrapper\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial-content\">Essendo l'unico vendor europeo presente nel\u00a0report di\u00a0quest'anno con un modello esclusivamente basato sui partner, consideriamo questo riconoscimento la prova che il nostro focus \u00e8 nella giusta direzione. Le\u00a0comunicazioni aziendali non dovrebbero limitarsi a connettere le persone, ma generare risultati misurabili. Ecco perch\u00e9 abbiamo sviluppato soluzioni pensate per i team di vendita e di prima linea che sono un motore fondamentale della crescita economica. Quando una clinica risponde a ogni chiamata o un commesso serve un cliente pi\u00f9 velocemente, il\u00a0ritorno \u00e8 immediato. \u00c8\u00a0su questo impatto che ci misuriamo\u00a0\u2014 ed\u00a0\u00e8\u00a0questa la visione che continueremo a\u00a0portare\u00a0avanti.\n<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-testimonial-meta elementor-has-image elementor-testimonial-image-position-aside\">\n\t\t\t\t<div class=\"elementor-testimonial-meta-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.wildix.com\/wp-content\/uploads\/2021\/03\/emiliano-tomasoni-smo-at-wildix-150x150.jpeg\" class=\"attachment-thumbnail size-thumbnail wp-image-7869499\" alt=\"Emiliano Tomasoni\" srcset=\"https:\/\/www.wildix.com\/wp-content\/uploads\/2021\/03\/emiliano-tomasoni-smo-at-wildix-150x150.jpeg 150w, https:\/\/www.wildix.com\/wp-content\/uploads\/2021\/03\/emiliano-tomasoni-smo-at-wildix-300x300.jpeg 300w, https:\/\/www.wildix.com\/wp-content\/uploads\/2021\/03\/emiliano-tomasoni-smo-at-wildix.jpeg 428w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-details\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-name\">Emiliano Tomasoni<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-job\">Chief Marketing Officer di\u00a0Wildix<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-81219ce elementor-widget elementor-widget-text-editor\" data-id=\"81219ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tNel corso dell&#8217;ultimo anno, Wildix ha arricchito la propria roadmap con innovazioni che potenziano la collaborazione, l&#8217;engagement dei clienti e le funzionalit\u00e0 di contact center lite. Tra\u00a0le\u00a0principali\u00a0novit\u00e0:\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-691d80d elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"691d80d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-right\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M285.476 272.971L91.132 467.314c-9.373 9.373-24.569 9.373-33.941 0l-22.667-22.667c-9.357-9.357-9.375-24.522-.04-33.901L188.505 256 34.484 101.255c-9.335-9.379-9.317-24.544.04-33.901l22.667-22.667c9.373-9.373 24.569-9.373 33.941 0L285.475 239.03c9.373 9.372 9.373 24.568.001 33.941z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Agenti AI multilingua<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-right\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M285.476 272.971L91.132 467.314c-9.373 9.373-24.569 9.373-33.941 0l-22.667-22.667c-9.357-9.357-9.375-24.522-.04-33.901L188.505 256 34.484 101.255c-9.335-9.379-9.317-24.544.04-33.901l22.667-22.667c9.373-9.373 24.569-9.373 33.941 0L285.475 239.03c9.373 9.372 9.373 24.568.001 33.941z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Branded calling nel Regno Unito, Stati Uniti e Germania<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-right\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M285.476 272.971L91.132 467.314c-9.373 9.373-24.569 9.373-33.941 0l-22.667-22.667c-9.357-9.357-9.375-24.522-.04-33.901L188.505 256 34.484 101.255c-9.335-9.379-9.317-24.544.04-33.901l22.667-22.667c9.373-9.373 24.569-9.373 33.941 0L285.475 239.03c9.373 9.372 9.373 24.568.001 33.941z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Adozione di\u00a0Wilma\u00a0AI, che\u00a0introduce automazione agentica in\u00a0tutto lo\u00a0stack\u00a0UCaaS<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-right\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M285.476 272.971L91.132 467.314c-9.373 9.373-24.569 9.373-33.941 0l-22.667-22.667c-9.357-9.357-9.375-24.522-.04-33.901L188.505 256 34.484 101.255c-9.335-9.379-9.317-24.544.04-33.901l22.667-22.667c9.373-9.373 24.569-9.373 33.941 0L285.475 239.03c9.373 9.372 9.373 24.568.001 33.941z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Miglioramenti al\u00a0prodotto omnicanale contact-center-lite, ampliando il\u00a0supporto ai\u00a0clienti<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-right\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M285.476 272.971L91.132 467.314c-9.373 9.373-24.569 9.373-33.941 0l-22.667-22.667c-9.357-9.357-9.375-24.522-.04-33.901L188.505 256 34.484 101.255c-9.335-9.379-9.317-24.544.04-33.901l22.667-22.667c9.373-9.373 24.569-9.373 33.941 0L285.475 239.03c9.373 9.372 9.373 24.568.001 33.941z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Espansione del\u00a0team globale di\u00a0Responsabili Tecnici Commerciali e\u00a0lancio della\u00a0Sales Academy, programma dedicato all\u2019abilitazione delle vendite UC che accelera l\u2019onboarding e\u00a0lo\u00a0sviluppo delle\u00a0competenze dei\u00a0partner<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-acaa925 elementor-widget elementor-widget-text-editor\" data-id=\"acaa925\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tI primi casi di implementazione mostrano i risultati concreti delle innovazioni di Wildix. In un recente progetto di distribuzione di Wilma\u00a0AI in 65\u00a0cliniche nel Regno Unito, la piattaforma ha permesso ai\u00a0team\u00a0di:\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ce24ce7 elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"ce24ce7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-right\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M285.476 272.971L91.132 467.314c-9.373 9.373-24.569 9.373-33.941 0l-22.667-22.667c-9.357-9.357-9.375-24.522-.04-33.901L188.505 256 34.484 101.255c-9.335-9.379-9.317-24.544.04-33.901l22.667-22.667c9.373-9.373 24.569-9.373 33.941 0L285.475 239.03c9.373 9.372 9.373 24.568.001 33.941z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Gestire oltre 50.000 chiamate senza perderne nessuna<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-right\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M285.476 272.971L91.132 467.314c-9.373 9.373-24.569 9.373-33.941 0l-22.667-22.667c-9.357-9.357-9.375-24.522-.04-33.901L188.505 256 34.484 101.255c-9.335-9.379-9.317-24.544.04-33.901l22.667-22.667c9.373-9.373 24.569-9.373 33.941 0L285.475 239.03c9.373 9.372 9.373 24.568.001 33.941z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Generare pi\u00f9 di\u00a09\u00a0milioni di\u00a0sterline in\u00a0nuovo valore per\u00a0i\u00a0pazienti<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-right\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M285.476 272.971L91.132 467.314c-9.373 9.373-24.569 9.373-33.941 0l-22.667-22.667c-9.357-9.357-9.375-24.522-.04-33.901L188.505 256 34.484 101.255c-9.335-9.379-9.317-24.544.04-33.901l22.667-22.667c9.373-9.373 24.569-9.373 33.941 0L285.475 239.03c9.373 9.372 9.373 24.568.001 33.941z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Liberare 2.000 ore di\u00a0lavoro restituite all\u2019assistenza diretta<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ff3bc73 elementor-widget elementor-widget-text-editor\" data-id=\"ff3bc73\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tIl portafoglio di Wildix comprende x\u2011bees per la collaborazione e l&#8217;engagement dei clienti, x\u2011hoppers per il retail di\u00a0prima linea e Wilma AI per l&#8217;automazione agentica integrata in tutte le soluzioni. Insieme, queste offerte estendono l&#8217;UCaaS oltre l&#8217;ufficio, raggiungendo ogni parte della forza lavoro. La\u00a0stessa piattaforma collega i team Wildix in tutte le regioni e i ruoli, rafforzando la solida cultura aziendale e l&#8217;elevata ritenzione dei dipendenti\u00a0\u2014 aspetti evidenziati nel report come motori della continua espansione globale\u00a0dell&#8217;azienda.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-38059c9 elementor-widget elementor-widget-text-editor\" data-id=\"38059c9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tIl riconoscimento arriva anche in vista dei prossimi <a href=\"https:\/\/www.wildix.com\/partner-day\/\">Global Partner Days<\/a>, durante i quali Wildix riunir\u00e0 i partner di tutto il mondo per allinearsi sulle strategie di crescita, condividere insight e presentare le ultime innovazioni\u00a0aziendali.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c0c5c48 e-con-full e-flex e-con e-child\" data-id=\"c0c5c48\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-aca977f elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"aca977f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f81b01e e-con-full e-flex e-con e-child\" data-id=\"f81b01e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9352c19 elementor-widget elementor-widget-text-editor\" data-id=\"9352c19\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tInformazioni su Wildix:\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-62348e1 elementor-widget elementor-widget-text-editor\" data-id=\"62348e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tWildix \u00e8 un fornitore globale di soluzioni UCaaS con un modello 100%\u00a0channel-first. Presente in oltre 135\u00a0paesi, serve pi\u00f9 di 1,5\u00a0milioni di utenti nei settori retail, sanit\u00e0 ed educazione. Le\u00a0sue soluzioni sicure e basate sull&#8217;intelligenza artificiale\u00a0\u2014 tra cui la piattaforma di riferimento x\u2011bees, potenziata da Wilma AI\u00a0\u2014 aiutano le aziende ad accelerare le vendite, ottimizzare le operazioni e adattarsi senza\u00a0frizioni.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-648b8d2 elementor-widget elementor-widget-text-editor\" data-id=\"648b8d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tMedia Contact:\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2275a75 elementor-mobile-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"2275a75\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-user\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224 256c70.7 0 128-57.3 128-128S294.7 0 224 0 96 57.3 96 128s57.3 128 128 128zm89.6 32h-16.7c-22.2 10.2-46.9 16-72.9 16s-50.6-5.8-72.9-16h-16.7C60.2 288 0 348.2 0 422.4V464c0 26.5 21.5 48 48 48h352c26.5 0 48-21.5 48-48v-41.6c0-74.2-60.2-134.4-134.4-134.4z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Deliah Mathieu, VP of Global Communications, Wildix<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"mailto:deliah.mathieu@wildix.com\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-envelope\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M502.3 190.8c3.9-3.1 9.7-.2 9.7 4.7V400c0 26.5-21.5 48-48 48H48c-26.5 0-48-21.5-48-48V195.6c0-5 5.7-7.8 9.7-4.7 22.4 17.4 52.1 39.5 154.1 113.6 21.1 15.4 56.7 47.8 92.2 47.6 35.7.3 72-32.8 92.3-47.6 102-74.1 131.6-96.3 154-113.7zM256 320c23.2.4 56.6-29.2 73.4-41.4 132.7-96.3 142.8-104.7 173.4-128.7 5.8-4.5 9.2-11.5 9.2-18.9v-19c0-26.5-21.5-48-48-48H48C21.5 64 0 85.5 0 112v19c0 7.4 3.4 14.3 9.2 18.9 30.6 23.9 40.7 32.4 173.4 128.7 16.8 12.2 50.2 41.8 73.4 41.4z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">deliah.mathieu@wildix.com<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b7e9cd4 e-con-full e-flex e-con e-child\" data-id=\"b7e9cd4\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-abbe732 elementor-widget elementor-widget-text-editor\" data-id=\"abbe732\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tDisclaimer Gartner:\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bd6a6d4 elementor-widget elementor-widget-text-editor\" data-id=\"bd6a6d4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tGartner, Magic\u00a0Quadrant for Unified Communications as\u00a0a\u00a0Service, Pankil\u00a0Sheth, Megan\u00a0Fernandez e altri contributori, 22\u00a0settembre\u00a02025, ID\u00a0G00823063.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a8015ac elementor-widget elementor-widget-text-editor\" data-id=\"a8015ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tGartner non avalla alcun fornitore, prodotto o servizio descritto nelle sue pubblicazioni di ricerca e non consiglia agli utenti di tecnologia di scegliere solo i fornitori con le valutazioni pi\u00f9 alte o con altre designazioni. Le\u00a0pubblicazioni di ricerca di Gartner riflettono le opinioni dell&#8217;organizzazione di ricerca di Gartner e non devono essere interpretate come dichiarazioni di fatto. Gartner declina tutte le garanzie, espresse o implicite, relative a questa ricerca, incluse eventuali garanzie di commerciabilit\u00e0 o idoneit\u00e0 per uno scopo\u00a0particolare.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Comunicato stampa Quinto anno consecutivo di\u00a0riconoscimento; ha\u00a0avanzato nella &#8220;Completeness of\u00a0Vision&#8221; rispetto al\u00a0posizionamento del\u00a02024 Tallinn, Estonia\u00a0\u2014 30\u00a0settembre\u00a02025\u00a0\u2014 Wildix, fornitore globale di soluzioni di comunicazione aziendale basate sull&#8217;intelligenza artificiale, ha annunciato oggi di essere stata riconosciuta come Niche Player nel Gartner\u00ae Magic Quadrant\u2122 2025 per Unified Communications as\u00a0a\u00a0Service (UCaaS).\u00c8 il quinto anno consecutivo che Wildix \u00e8\u00a0inclusa nel\u00a0report, [&hellip;]<\/p>\n","protected":false},"author":51,"featured_media":8166623,"parent":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_jet_sm_ready_style":"","_jet_sm_style":"","_jet_sm_controls_values":"","_jet_sm_fonts_collection":"","_jet_sm_fonts_links":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[364],"tags":[],"class_list":["post-8166400","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news-it"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Wildix riconosciuta nel\u00a0Gartner\u00ae Magic\u00a0Quadrant\u2122\u00a02025 per Unified Communications as\u00a0a\u00a0Service\u00a0(UCaaS) | Wildix<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wildix riconosciuta nel\u00a0Gartner\u00ae Magic\u00a0Quadrant\u2122\u00a02025 per Unified Communications as\u00a0a\u00a0Service\u00a0(UCaaS) | Wildix\" \/>\n<meta property=\"og:description\" content=\"Comunicato stampa Quinto anno consecutivo di\u00a0riconoscimento; ha\u00a0avanzato nella &#8220;Completeness of\u00a0Vision&#8221; rispetto al\u00a0posizionamento del\u00a02024 Tallinn, Estonia\u00a0\u2014 30\u00a0settembre\u00a02025\u00a0\u2014 Wildix, fornitore globale di soluzioni di comunicazione aziendale basate sull&#8217;intelligenza artificiale, ha annunciato oggi di essere stata riconosciuta come Niche Player nel Gartner\u00ae Magic Quadrant\u2122 2025 per Unified Communications as\u00a0a\u00a0Service (UCaaS).\u00c8 il quinto anno consecutivo che Wildix \u00e8\u00a0inclusa nel\u00a0report, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.wildix.com\/it\/wildix-riconosciuta-nel-gartner-magic-quadrant-2025-per-unified-communications-as-a-service-ucaas\/\" \/>\n<meta property=\"og:site_name\" content=\"Wildix\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/groups\/wildixtechwizards\/?mibextid=6NoCDW\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-01T14:36:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-07T16:29:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.wildix.com\/wp-content\/uploads\/2025\/10\/Wildix-Gartner-Magic-Quadrant-2025-PR-IT.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Oksana Troshyna\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@wildix_\" \/>\n<meta name=\"twitter:site\" content=\"@wildix_\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Oksana Troshyna\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wildix riconosciuta nel\u00a0Gartner\u00ae Magic\u00a0Quadrant\u2122\u00a02025 per Unified Communications as\u00a0a\u00a0Service\u00a0(UCaaS) | Wildix","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"it_IT","og_type":"article","og_title":"Wildix riconosciuta nel\u00a0Gartner\u00ae Magic\u00a0Quadrant\u2122\u00a02025 per Unified Communications as\u00a0a\u00a0Service\u00a0(UCaaS) | Wildix","og_description":"Comunicato stampa Quinto anno consecutivo di\u00a0riconoscimento; ha\u00a0avanzato nella &#8220;Completeness of\u00a0Vision&#8221; rispetto al\u00a0posizionamento del\u00a02024 Tallinn, Estonia\u00a0\u2014 30\u00a0settembre\u00a02025\u00a0\u2014 Wildix, fornitore globale di soluzioni di comunicazione aziendale basate sull&#8217;intelligenza artificiale, ha annunciato oggi di essere stata riconosciuta come Niche Player nel Gartner\u00ae Magic Quadrant\u2122 2025 per Unified Communications as\u00a0a\u00a0Service (UCaaS).\u00c8 il quinto anno consecutivo che Wildix \u00e8\u00a0inclusa nel\u00a0report, [&hellip;]","og_url":"https:\/\/www.wildix.com\/it\/wildix-riconosciuta-nel-gartner-magic-quadrant-2025-per-unified-communications-as-a-service-ucaas\/","og_site_name":"Wildix","article_publisher":"https:\/\/www.facebook.com\/groups\/wildixtechwizards\/?mibextid=6NoCDW","article_published_time":"2025-10-01T14:36:58+00:00","article_modified_time":"2025-10-07T16:29:09+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.wildix.com\/wp-content\/uploads\/2025\/10\/Wildix-Gartner-Magic-Quadrant-2025-PR-IT.webp","type":"image\/webp"}],"author":"Oksana Troshyna","twitter_card":"summary_large_image","twitter_creator":"@wildix_","twitter_site":"@wildix_","twitter_misc":{"Scritto da":"Oksana Troshyna","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.wildix.com\/it\/wildix-riconosciuta-nel-gartner-magic-quadrant-2025-per-unified-communications-as-a-service-ucaas\/#article","isPartOf":{"@id":"https:\/\/www.wildix.com\/it\/wildix-riconosciuta-nel-gartner-magic-quadrant-2025-per-unified-communications-as-a-service-ucaas\/"},"author":{"name":"Oksana Troshyna","@id":"https:\/\/www.wildix.com\/it\/#\/schema\/person\/6c8661146e4fc1b692f037dcbe713c41"},"headline":"Wildix riconosciuta nel\u00a0Gartner\u00ae Magic\u00a0Quadrant\u2122\u00a02025 per Unified Communications as\u00a0a\u00a0Service\u00a0(UCaaS)","datePublished":"2025-10-01T14:36:58+00:00","dateModified":"2025-10-07T16:29:09+00:00","mainEntityOfPage":{"@id":"https:\/\/www.wildix.com\/it\/wildix-riconosciuta-nel-gartner-magic-quadrant-2025-per-unified-communications-as-a-service-ucaas\/"},"wordCount":725,"publisher":{"@id":"https:\/\/www.wildix.com\/it\/#organization"},"image":{"@id":"https:\/\/www.wildix.com\/it\/wildix-riconosciuta-nel-gartner-magic-quadrant-2025-per-unified-communications-as-a-service-ucaas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.wildix.com\/wp-content\/uploads\/2025\/10\/Wildix-Gartner-Magic-Quadrant-2025-PR-IT.webp","articleSection":["News ITA"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.wildix.com\/it\/wildix-riconosciuta-nel-gartner-magic-quadrant-2025-per-unified-communications-as-a-service-ucaas\/","url":"https:\/\/www.wildix.com\/it\/wildix-riconosciuta-nel-gartner-magic-quadrant-2025-per-unified-communications-as-a-service-ucaas\/","name":"Wildix riconosciuta nel\u00a0Gartner\u00ae Magic\u00a0Quadrant\u2122\u00a02025 per Unified Communications as\u00a0a\u00a0Service\u00a0(UCaaS) | Wildix","isPartOf":{"@id":"https:\/\/www.wildix.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.wildix.com\/it\/wildix-riconosciuta-nel-gartner-magic-quadrant-2025-per-unified-communications-as-a-service-ucaas\/#primaryimage"},"image":{"@id":"https:\/\/www.wildix.com\/it\/wildix-riconosciuta-nel-gartner-magic-quadrant-2025-per-unified-communications-as-a-service-ucaas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.wildix.com\/wp-content\/uploads\/2025\/10\/Wildix-Gartner-Magic-Quadrant-2025-PR-IT.webp","datePublished":"2025-10-01T14:36:58+00:00","dateModified":"2025-10-07T16:29:09+00:00","breadcrumb":{"@id":"https:\/\/www.wildix.com\/it\/wildix-riconosciuta-nel-gartner-magic-quadrant-2025-per-unified-communications-as-a-service-ucaas\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.wildix.com\/it\/wildix-riconosciuta-nel-gartner-magic-quadrant-2025-per-unified-communications-as-a-service-ucaas\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.wildix.com\/it\/wildix-riconosciuta-nel-gartner-magic-quadrant-2025-per-unified-communications-as-a-service-ucaas\/#primaryimage","url":"https:\/\/www.wildix.com\/wp-content\/uploads\/2025\/10\/Wildix-Gartner-Magic-Quadrant-2025-PR-IT.webp","contentUrl":"https:\/\/www.wildix.com\/wp-content\/uploads\/2025\/10\/Wildix-Gartner-Magic-Quadrant-2025-PR-IT.webp","width":1200,"height":630,"caption":"Wildix Gartner Magic Quadrant 2025 PR IT"},{"@type":"BreadcrumbList","@id":"https:\/\/www.wildix.com\/it\/wildix-riconosciuta-nel-gartner-magic-quadrant-2025-per-unified-communications-as-a-service-ucaas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.wildix.com\/it\/"},{"@type":"ListItem","position":2,"name":"Wildix riconosciuta nel\u00a0Gartner\u00ae Magic\u00a0Quadrant\u2122\u00a02025 per Unified Communications as\u00a0a\u00a0Service\u00a0(UCaaS)"}]},{"@type":"WebSite","@id":"https:\/\/www.wildix.com\/it\/#website","url":"https:\/\/www.wildix.com\/it\/","name":"Wildix","description":"","publisher":{"@id":"https:\/\/www.wildix.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.wildix.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.wildix.com\/it\/#organization","name":"Wildix","url":"https:\/\/www.wildix.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.wildix.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.wildix.com\/wp-content\/uploads\/2021\/09\/logo-1.svg","contentUrl":"https:\/\/www.wildix.com\/wp-content\/uploads\/2021\/09\/logo-1.svg","caption":"Wildix"},"image":{"@id":"https:\/\/www.wildix.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/groups\/wildixtechwizards\/?mibextid=6NoCDW","https:\/\/x.com\/wildix_"]},{"@type":"Person","@id":"https:\/\/www.wildix.com\/it\/#\/schema\/person\/6c8661146e4fc1b692f037dcbe713c41","name":"Oksana Troshyna","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/9576dcb9c3d786b0c81f0e89e9d2f0866d5348775664c07b0ee35e68afa7475a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9576dcb9c3d786b0c81f0e89e9d2f0866d5348775664c07b0ee35e68afa7475a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9576dcb9c3d786b0c81f0e89e9d2f0866d5348775664c07b0ee35e68afa7475a?s=96&d=mm&r=g","caption":"Oksana Troshyna"}}]}},"clean_content":"Comunicato stampa Quinto anno consecutivo di\u00a0riconoscimento; ha\u00a0avanzato nella \"Completeness of\u00a0Vision\" rispetto al\u00a0posizionamento del\u00a02024 Tallinn, Estonia\u00a0\u2014 30\u00a0settembre\u00a02025\u00a0\u2014 Wildix, fornitore globale di soluzioni di comunicazione aziendale basate sull\u2019intelligenza artificiale, ha annunciato oggi di essere stata riconosciuta come Niche Player nel Gartner\u00ae Magic Quadrant\u2122 2025 per Unified Communications as\u00a0a\u00a0Service (UCaaS). \u00c8 il quinto anno consecutivo che Wildix \u00e8\u00a0inclusa nel\u00a0report, rimanendo l\u2019unico vendor europeo\u00a0riconosciuto. Nell\u2019edizione 2025, Wildix ha inoltre avanzato ulteriormente sull\u2019asse della \u201cCompleteness of Vision\u201d all\u2019interno del quadrante dei\u00a0Niche Players, migliorando la\u00a0propria posizione rispetto al\u00a02024. Il modello Wildix si distingue per l\u2019attenzione rivolta alle medie imprese, alle organizzazioni orientate alle vendite e ai settori con una forte presenza di personale operativo. Con una solida base in Europa e una crescita costante in Nord America, l\u2019azienda continua a rafforzare la\u00a0propria presenza\u00a0globale. Essendo l'unico vendor europeo presente nel\u00a0report di\u00a0quest'anno con un modello esclusivamente basato sui partner, consideriamo questo riconoscimento la prova che il nostro focus \u00e8 nella giusta direzione. Le\u00a0comunicazioni aziendali non dovrebbero limitarsi a connettere le persone, ma generare risultati misurabili. Ecco perch\u00e9 abbiamo sviluppato soluzioni pensate per i team di vendita e di prima linea che sono un motore fondamentale della crescita economica. Quando una clinica risponde a ogni chiamata o un commesso serve un cliente pi\u00f9 velocemente, il\u00a0ritorno \u00e8 immediato. \u00c8\u00a0su questo impatto che ci misuriamo\u00a0\u2014 ed\u00a0\u00e8\u00a0questa la visione che continueremo a\u00a0portare\u00a0avanti. Emiliano Tomasoni Chief Marketing Officer di\u00a0Wildix Nel corso dell\u2019ultimo anno, Wildix ha arricchito la propria roadmap con innovazioni che potenziano la collaborazione, l\u2019engagement dei clienti e le funzionalit\u00e0 di contact center lite. Tra\u00a0le\u00a0principali\u00a0novit\u00e0: Agenti AI multilingua Branded calling nel Regno Unito, Stati Uniti e Germania Adozione di\u00a0Wilma\u00a0AI, che\u00a0introduce automazione agentica in\u00a0tutto lo\u00a0stack\u00a0UCaaS Miglioramenti al\u00a0prodotto omnicanale contact-center-lite, ampliando il\u00a0supporto ai\u00a0clienti Espansione del\u00a0team globale di\u00a0Responsabili Tecnici Commerciali e\u00a0lancio della\u00a0Sales Academy, programma dedicato all\u2019abilitazione delle vendite UC che accelera l\u2019onboarding e\u00a0lo\u00a0sviluppo delle\u00a0competenze dei\u00a0partner I primi casi di implementazione mostrano i risultati concreti delle innovazioni di Wildix. In un recente progetto di distribuzione di Wilma\u00a0AI in 65\u00a0cliniche nel Regno Unito, la piattaforma ha permesso ai\u00a0team\u00a0di: Gestire oltre 50.000 chiamate senza perderne nessuna Generare pi\u00f9 di\u00a09\u00a0milioni di\u00a0sterline in\u00a0nuovo valore per\u00a0i\u00a0pazienti Liberare 2.000 ore di\u00a0lavoro restituite all\u2019assistenza diretta Il portafoglio di Wildix comprende x\u2011bees per la collaborazione e l\u2019engagement dei clienti, x\u2011hoppers per il retail di\u00a0prima linea e Wilma AI per l\u2019automazione agentica integrata in tutte le soluzioni. Insieme, queste offerte estendono l\u2019UCaaS oltre l\u2019ufficio, raggiungendo ogni parte della forza lavoro. La\u00a0stessa piattaforma collega i team Wildix in tutte le regioni e i ruoli, rafforzando la solida cultura aziendale e l\u2019elevata ritenzione dei dipendenti\u00a0\u2014 aspetti evidenziati nel report come motori della continua espansione globale\u00a0dell\u2019azienda. Il riconoscimento arriva anche in vista dei prossimi Global Partner Days, durante i quali Wildix riunir\u00e0 i partner di tutto il mondo per allinearsi sulle strategie di crescita, condividere insight e presentare le ultime innovazioni\u00a0aziendali. Informazioni su Wildix: Wildix \u00e8 un fornitore globale di soluzioni UCaaS con un modello 100%\u00a0channel-first. Presente in oltre 135\u00a0paesi, serve pi\u00f9 di 1,5\u00a0milioni di utenti nei settori retail, sanit\u00e0 ed educazione. Le\u00a0sue soluzioni sicure e basate sull\u2019intelligenza artificiale\u00a0\u2014 tra cui la piattaforma di riferimento x\u2011bees, potenziata da Wilma AI\u00a0\u2014 aiutano le aziende ad accelerare le vendite, ottimizzare le operazioni e adattarsi senza\u00a0frizioni. Media Contact: Deliah Mathieu, VP of Global Communications, Wildix deliah.mathieu@wildix.com Disclaimer Gartner: Gartner, Magic\u00a0Quadrant for Unified Communications as\u00a0a\u00a0Service, Pankil\u00a0Sheth, Megan\u00a0Fernandez e altri contributori, 22\u00a0settembre\u00a02025, ID\u00a0G00823063. Gartner non avalla alcun fornitore, prodotto o servizio descritto nelle sue pubblicazioni di ricerca e non consiglia agli utenti di tecnologia di scegliere solo i fornitori con le valutazioni pi\u00f9 alte o con altre designazioni. Le\u00a0pubblicazioni di ricerca di Gartner riflettono le opinioni dell\u2019organizzazione di ricerca di Gartner e non devono essere interpretate come dichiarazioni di fatto. Gartner declina tutte le garanzie, espresse o implicite, relative a questa ricerca, incluse eventuali garanzie di commerciabilit\u00e0 o idoneit\u00e0 per uno scopo\u00a0particolare.","clean_excerpt":"Comunicato stampa Quinto anno consecutivo di\u00a0riconoscimento; ha\u00a0avanzato nella \"Completeness of\u00a0Vision\" rispetto al\u00a0posizionamento del\u00a02024 Tallinn, Estonia\u00a0\u2014 30\u00a0settembre\u00a02025\u00a0\u2014 Wildix, fornitore globale di soluzioni di comunicazione aziendale basate sull'intelligenza artificiale, ha annunciato oggi di essere stata riconosciuta come Niche Player nel Gartner\u00ae Magic Quadrant\u2122 2025 per Unified Communications as\u00a0a\u00a0Service (UCaaS).\u00c8 il quinto anno consecutivo che Wildix \u00e8\u00a0inclusa nel\u00a0report,...","_links":{"self":[{"href":"https:\/\/www.wildix.com\/it\/wp-json\/wp\/v2\/posts\/8166400","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.wildix.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.wildix.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.wildix.com\/it\/wp-json\/wp\/v2\/users\/51"}],"replies":[{"embeddable":true,"href":"https:\/\/www.wildix.com\/it\/wp-json\/wp\/v2\/comments?post=8166400"}],"version-history":[{"count":5,"href":"https:\/\/www.wildix.com\/it\/wp-json\/wp\/v2\/posts\/8166400\/revisions"}],"predecessor-version":[{"id":8166632,"href":"https:\/\/www.wildix.com\/it\/wp-json\/wp\/v2\/posts\/8166400\/revisions\/8166632"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.wildix.com\/it\/wp-json\/wp\/v2\/media\/8166623"}],"wp:attachment":[{"href":"https:\/\/www.wildix.com\/it\/wp-json\/wp\/v2\/media?parent=8166400"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.wildix.com\/it\/wp-json\/wp\/v2\/categories?post=8166400"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.wildix.com\/it\/wp-json\/wp\/v2\/tags?post=8166400"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}