{"id":7914109,"date":"2018-07-24T10:06:11","date_gmt":"2018-07-24T08:06:11","guid":{"rendered":"https:\/\/www.wildix.com\/rassegna-stampa-giugno-2018\/"},"modified":"2022-07-15T16:16:20","modified_gmt":"2022-07-15T14:16:20","slug":"rassegna-stampa-giugno-2018","status":"publish","type":"post","link":"https:\/\/www.wildix.com\/it\/rassegna-stampa-giugno-2018\/","title":{"rendered":"Rassegna stampa Giugno 2018"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"7914109\" class=\"elementor elementor-7914109\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-11bcf39e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"11bcf39e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-66cdbde\" data-id=\"66cdbde\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dcdeef2 elementor-widget elementor-widget-text-editor\" data-id=\"dcdeef2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Protagonista assoluto della rassegna stampa di Giugno \u00e8 il <strong>CEBIT di Hannover<\/strong>, la pi\u00f9 importante fiera al mondo dedicata all\u2019 information and communication technology.<\/p><p>In questa cornice prestigiosa Wildix ha presentato <strong>il nuovo telefono SuperVision<\/strong>, il pi\u00f9 esclusivo e performante della gamma. E\u2019 un terminale indirizzato ai top manager, dotato di schermo di 8 pollici, sistema operativo Android, web cam rimovibile per garantire totale sicurezza e sostituibile con camera wide angle 120\u00b0 per videoconferenza (opzionale).<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fde8015 elementor-widget elementor-widget-html\" data-id=\"fde8015\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<iframe src=\"\/\/www.slideshare.net\/slideshow\/embed_code\/key\/KklqkT4FEGqhSm\" width=\"668\" height=\"714\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" style=\"border:1px solid #CCC; border-width:1px; margin-bottom:5px; max-width: 100%;\" allowfullscreen> <\/iframe> <div style=\"margin-bottom:5px\"> <strong> <a href=\"\/\/www.slideshare.net\/Wildix\/italy-coverage-bookgiugno18\" title=\"Wildix - Rassegna stampa - giugno 18\" target=\"_blank\">Wildix - Rassegna stampa - giugno 18<\/a> <\/strong> from <strong><a href=\"\/\/www.slideshare.net\/Wildix\" target=\"_blank\">Wildix<\/a><\/strong> <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Protagonista assoluto della rassegna stampa di Giugno \u00e8 il CEBIT di Hannover, la pi\u00f9 importante fiera al mondo dedicata all\u2019 information and communication technology.<\/p>\n","protected":false},"author":20,"featured_media":7913927,"parent":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_jet_sm_ready_style":"","_jet_sm_style":"","_jet_sm_controls_values":"","_jet_sm_fonts_collection":"","_jet_sm_fonts_links":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[364],"tags":[],"class_list":["post-7914109","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news-it"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rassegna stampa Giugno 2018 | Wildix<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rassegna stampa Giugno 2018 | Wildix\" \/>\n<meta property=\"og:description\" content=\"Protagonista assoluto della rassegna stampa di Giugno \u00e8 il CEBIT di Hannover, la pi\u00f9 importante fiera al mondo dedicata all\u2019 information and communication technology.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.wildix.com\/it\/rassegna-stampa-giugno-2018\/\" \/>\n<meta property=\"og:site_name\" content=\"Wildix\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/groups\/wildixtechwizards\/?mibextid=6NoCDW\" \/>\n<meta property=\"article:published_time\" content=\"2018-07-24T08:06:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-15T14:16:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.wildix.com\/wp-content\/uploads\/2022\/05\/supervision-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"575\" \/>\n\t<meta property=\"og:image:height\" content=\"416\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ivan Michelazzi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@wildix_\" \/>\n<meta name=\"twitter:site\" content=\"@wildix_\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ivan Michelazzi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rassegna stampa Giugno 2018 | Wildix","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"it_IT","og_type":"article","og_title":"Rassegna stampa Giugno 2018 | Wildix","og_description":"Protagonista assoluto della rassegna stampa di Giugno \u00e8 il CEBIT di Hannover, la pi\u00f9 importante fiera al mondo dedicata all\u2019 information and communication technology.","og_url":"https:\/\/www.wildix.com\/it\/rassegna-stampa-giugno-2018\/","og_site_name":"Wildix","article_publisher":"https:\/\/www.facebook.com\/groups\/wildixtechwizards\/?mibextid=6NoCDW","article_published_time":"2018-07-24T08:06:11+00:00","article_modified_time":"2022-07-15T14:16:20+00:00","og_image":[{"width":575,"height":416,"url":"https:\/\/www.wildix.com\/wp-content\/uploads\/2022\/05\/supervision-1.jpg","type":"image\/jpeg"}],"author":"Ivan Michelazzi","twitter_card":"summary_large_image","twitter_creator":"@wildix_","twitter_site":"@wildix_","twitter_misc":{"Scritto da":"Ivan Michelazzi","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.wildix.com\/it\/rassegna-stampa-giugno-2018\/#article","isPartOf":{"@id":"https:\/\/www.wildix.com\/it\/rassegna-stampa-giugno-2018\/"},"author":{"name":"Ivan Michelazzi","@id":"https:\/\/www.wildix.com\/it\/#\/schema\/person\/b1a7a7b15f760c50de71110bbde7b523"},"headline":"Rassegna stampa Giugno 2018","datePublished":"2018-07-24T08:06:11+00:00","dateModified":"2022-07-15T14:16:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.wildix.com\/it\/rassegna-stampa-giugno-2018\/"},"wordCount":83,"commentCount":0,"publisher":{"@id":"https:\/\/www.wildix.com\/it\/#organization"},"image":{"@id":"https:\/\/www.wildix.com\/it\/rassegna-stampa-giugno-2018\/#primaryimage"},"thumbnailUrl":"https:\/\/www.wildix.com\/wp-content\/uploads\/2022\/05\/supervision-1.jpg","articleSection":["News ITA"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.wildix.com\/it\/rassegna-stampa-giugno-2018\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.wildix.com\/it\/rassegna-stampa-giugno-2018\/","url":"https:\/\/www.wildix.com\/it\/rassegna-stampa-giugno-2018\/","name":"Rassegna stampa Giugno 2018 | Wildix","isPartOf":{"@id":"https:\/\/www.wildix.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.wildix.com\/it\/rassegna-stampa-giugno-2018\/#primaryimage"},"image":{"@id":"https:\/\/www.wildix.com\/it\/rassegna-stampa-giugno-2018\/#primaryimage"},"thumbnailUrl":"https:\/\/www.wildix.com\/wp-content\/uploads\/2022\/05\/supervision-1.jpg","datePublished":"2018-07-24T08:06:11+00:00","dateModified":"2022-07-15T14:16:20+00:00","breadcrumb":{"@id":"https:\/\/www.wildix.com\/it\/rassegna-stampa-giugno-2018\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.wildix.com\/it\/rassegna-stampa-giugno-2018\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.wildix.com\/it\/rassegna-stampa-giugno-2018\/#primaryimage","url":"https:\/\/www.wildix.com\/wp-content\/uploads\/2022\/05\/supervision-1.jpg","contentUrl":"https:\/\/www.wildix.com\/wp-content\/uploads\/2022\/05\/supervision-1.jpg","width":575,"height":416},{"@type":"BreadcrumbList","@id":"https:\/\/www.wildix.com\/it\/rassegna-stampa-giugno-2018\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.wildix.com\/it\/"},{"@type":"ListItem","position":2,"name":"Rassegna stampa Giugno 2018"}]},{"@type":"WebSite","@id":"https:\/\/www.wildix.com\/it\/#website","url":"https:\/\/www.wildix.com\/it\/","name":"Wildix","description":"","publisher":{"@id":"https:\/\/www.wildix.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.wildix.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.wildix.com\/it\/#organization","name":"Wildix","url":"https:\/\/www.wildix.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.wildix.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.wildix.com\/wp-content\/uploads\/2021\/09\/logo-1.svg","contentUrl":"https:\/\/www.wildix.com\/wp-content\/uploads\/2021\/09\/logo-1.svg","caption":"Wildix"},"image":{"@id":"https:\/\/www.wildix.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/groups\/wildixtechwizards\/?mibextid=6NoCDW","https:\/\/x.com\/wildix_"]},{"@type":"Person","@id":"https:\/\/www.wildix.com\/it\/#\/schema\/person\/b1a7a7b15f760c50de71110bbde7b523","name":"Ivan Michelazzi","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c27dfefd7e146431d0cff8e02c3d7e9059d7015a9be1cebcdaa47131a73cd65f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c27dfefd7e146431d0cff8e02c3d7e9059d7015a9be1cebcdaa47131a73cd65f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c27dfefd7e146431d0cff8e02c3d7e9059d7015a9be1cebcdaa47131a73cd65f?s=96&d=mm&r=g","caption":"Ivan Michelazzi"}}]}},"clean_content":"Protagonista assoluto della rassegna stampa di Giugno \u00e8 il CEBIT di Hannover, la pi\u00f9 importante fiera al mondo dedicata all\u2019 information and communication technology.In questa cornice prestigiosa Wildix ha presentato il nuovo telefono SuperVision, il pi\u00f9 esclusivo e performante della gamma. E\u2019 un terminale indirizzato ai top manager, dotato di schermo di 8 pollici, sistema operativo Android, web cam rimovibile per garantire totale sicurezza e sostituibile con camera wide angle 120\u00b0 per videoconferenza (opzionale). Wildix - Rassegna stampa - giugno 18 from Wildix","clean_excerpt":"Protagonista assoluto della rassegna stampa di Giugno \u00e8 il CEBIT di Hannover, la pi\u00f9 importante fiera al mondo dedicata all\u2019 information and communication technology.","_links":{"self":[{"href":"https:\/\/www.wildix.com\/it\/wp-json\/wp\/v2\/posts\/7914109","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.wildix.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.wildix.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.wildix.com\/it\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/www.wildix.com\/it\/wp-json\/wp\/v2\/comments?post=7914109"}],"version-history":[{"count":0,"href":"https:\/\/www.wildix.com\/it\/wp-json\/wp\/v2\/posts\/7914109\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.wildix.com\/it\/wp-json\/wp\/v2\/media\/7913927"}],"wp:attachment":[{"href":"https:\/\/www.wildix.com\/it\/wp-json\/wp\/v2\/media?parent=7914109"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.wildix.com\/it\/wp-json\/wp\/v2\/categories?post=7914109"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.wildix.com\/it\/wp-json\/wp\/v2\/tags?post=7914109"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}