{"id":8037886,"date":"2023-05-30T11:40:39","date_gmt":"2023-05-30T09:40:39","guid":{"rendered":"https:\/\/www.wildix.com\/10-years-webrtc-celebration\/"},"modified":"2024-03-19T11:24:28","modified_gmt":"2024-03-19T10:24:28","slug":"celebration-10-annees-webrtc","status":"publish","type":"post","link":"https:\/\/www.wildix.com\/fr\/celebration-10-annees-webrtc\/","title":{"rendered":"Wildix c\u00e9l\u00e8bre les 10 ans du WebRTC"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"8037886\" class=\"elementor elementor-8037886 elementor-8037782\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-efb3920 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"efb3920\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-20cf8a9\" data-id=\"20cf8a9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-607a5311 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"607a5311\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-326a7865\" data-id=\"326a7865\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-27292b3d elementor-widget elementor-widget-text-editor\" data-id=\"27292b3d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<span style=\"background-color: #003366; color: #ffffff; padding: 10px 10px 10px 10px; border-radius: 3px;\">Communiqu\u00e9 de Presse <\/span>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-5baaac56 elementor-widget elementor-widget-heading\" data-id=\"5baaac56\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Wildix c\u00e9l\u00e8bre les 10 ans du WebRTC<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4d903abd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4d903abd\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-2e1d70fd\" data-id=\"2e1d70fd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-60daf0d3 elementor-widget elementor-widget-text-editor\" data-id=\"60daf0d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tTallinn, Estonie &#8211; 30 mai 2023 &#8211; Wildix est heureux de c\u00e9l\u00e9brer son 10e anniversaire avec le WebRTC. La technologie de communication dans le navigateur est essentielle pour les communications unifi\u00e9es modernes, et elle est maintenant largement adopt\u00e9e par les fournisseurs. \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-58ba14fd elementor-widget elementor-widget-text-editor\" data-id=\"58ba14fd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tL&#8217;objectif du WebRTC \u00e9tait de mettre en \u0153uvre des communications en temps r\u00e9el \u00e0 travers plusieurs navigateurs, r\u00e9duisant ainsi le temps que les d\u00e9veloppeurs doivent consacrer \u00e0 la programmation. \u00c0 l&#8217;instar du HTML et du texte qui sont devenus ouverts et accessibles \u00e0 tous, le WebRTC avait pour objectif de d\u00e9mocratiser la vid\u00e9o et la voix.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-63f4e17a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"63f4e17a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-6ae7f47f\" data-id=\"6ae7f47f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7ea7d64f testimonials-block elementor-widget elementor-widget-testimonial\" data-id=\"7ea7d64f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"testimonial.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial-wrapper\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial-content\">\"Nous \u00e9tions convaincus que les communications unifi\u00e9es bas\u00e9es sur le web \u00e9taient la voie \u00e0 suivre, et notre premier client de communications unifi\u00e9es en 2009 \u00e9tait \u00e9galement enti\u00e8rement bas\u00e9 sur les technologies web\", a d\u00e9clar\u00e9 Dimitri Osler, CTO et fondateur de Wildix. \"Lorsque nous avons d\u00e9couvert le WebRTC, nous avons imm\u00e9diatement vu son potentiel et nous avons saut\u00e9 dans le train en marche pour cr\u00e9er des clients capables de l'utiliser. Dix ans plus tard, nous n'avons pas regard\u00e9 derri\u00e8re nous. <\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-testimonial-meta elementor-has-image elementor-testimonial-image-position-aside\">\n\t\t\t\t<div class=\"elementor-testimonial-meta-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.wildix.com\/wp-content\/uploads\/2022\/07\/dimitri-osler-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-image-7966305\" alt=\"Dimitri Osler\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-details\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-name\">Dimitri Osler,<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-job\"> CTO et fondateur de Wildix<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-59e1264a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"59e1264a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-226191fb\" data-id=\"226191fb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2d10501e elementor-widget elementor-widget-text-editor\" data-id=\"2d10501e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tLe WebRTC est l&#8217;une des nombreuses technologies de base sur lesquelles reposent les services de Wildix, qui comprennent Collaboration, Wizyconf, Wizywebinar, x-bees, Kite et x-hoppers. Aujourd&#8217;hui encore, Wildix est l&#8217;un des rares services \u00e0 utiliser le WebRTC pour autre chose que le trunking, et beaucoup ne l&#8217;utilisent que pour l&#8217;audio. Avec les solutions Wildix, le WebRTC est m\u00eame utilis\u00e9 pour le contr\u00f4le d&#8217;\u00e9cran \u00e0 distance, ce qui d\u00e9montre son potentiel. \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c8ce9f1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c8ce9f1\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-857f2bf\" data-id=\"857f2bf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5993102 elementor-widget elementor-widget-text-editor\" data-id=\"5993102\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t&#8220;L&#8217;utilisation du WebRTC signifie que nous n&#8217;avons pas besoin de cr\u00e9er un client en dur, ce qui simplifie le d\u00e9ploiement sur plusieurs syst\u00e8mes&#8221;, poursuit Dimitri. &#8220;La croissance du WebRTC et de Google Chrome permet \u00e0 nos solutions d&#8217;\u00eatre adapt\u00e9es pour \u00eatre utilis\u00e9es dans une vari\u00e9t\u00e9 d&#8217;environnements, et comme d&#8217;autres navigateurs ont ajout\u00e9 la prise en charge, nous pourrions d\u00e9ployer sur ces navigateurs sans plugins ni API suppl\u00e9mentaires.&#8221;\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-96d3f84 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"96d3f84\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-12c5ab9\" data-id=\"12c5ab9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-91cb262 elementor-widget elementor-widget-text-editor\" data-id=\"91cb262\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tWildix compte aujourd&#8217;hui plus d&#8217;un million de d\u00e9ploiements bas\u00e9s sur le WebRTC, avec des utilisateurs finaux qui se connectent \u00e0 leurs clients, coll\u00e8gues et autres parties par le biais d&#8217;engagements de navigateur \u00e0 navigateur et par l&#8217;interm\u00e9diaire de liaisons SIP.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-8dd111c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8dd111c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-66911e0\" data-id=\"66911e0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a45fac9 elementor-widget elementor-widget-text-editor\" data-id=\"a45fac9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t&#8220;Le WebRTC a explos\u00e9 en popularit\u00e9 et est devenu la norme qui facilite la connexion&#8221;, note Dimitri. &#8220;Nous sommes fiers d&#8217;avoir ouvert la voie et d&#8217;avoir d\u00e9velopp\u00e9 cette solution en profondeur, et nous sommes reconnaissants \u00e0 tous ceux qui ont rendu cela possible.&#8221; \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b473186 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b473186\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-6601414\" data-id=\"6601414\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f33c944 elementor-widget elementor-widget-text-editor\" data-id=\"f33c944\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Pour plus d&#8217;informations sur Wildix et nos solutions WebRTC, <a href=\"https:\/\/www.wildix.com\/fr\/product\/plateforme-collaboration-ucc\/\">cliquez ici<\/a>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-9c4e908 e-flex e-con-boxed e-con e-parent\" data-id=\"9c4e908\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Communiqu\u00e9 de Presse Wildix c\u00e9l\u00e8bre les 10 ans du WebRTC Tallinn, Estonie &#8211; 30 mai 2023 &#8211; Wildix est heureux de c\u00e9l\u00e9brer son 10e anniversaire avec le WebRTC. La technologie de communication dans le navigateur est essentielle pour les communications unifi\u00e9es modernes, et elle est maintenant largement adopt\u00e9e par les fournisseurs. L&#8217;objectif du WebRTC \u00e9tait [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":8037817,"parent":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_jet_sm_ready_style":"","_jet_sm_style":"","_jet_sm_controls_values":"","_jet_sm_fonts_collection":"","_jet_sm_fonts_links":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[366],"tags":[],"class_list":["post-8037886","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news-fra"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>10 ann\u00e9es de WebRTC | Wildix<\/title>\n<meta name=\"description\" content=\"En d\u00e9ployant tr\u00e8s t\u00f4t des solutions WebRTC, Wildix a ouvert la voie \u00e0 l&#039;adoption par les UCC de cette technologie vitale et flexible. Aujourd&#039;hui, nous f\u00eatons nos 10 ans d&#039;utilisation.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"10 ann\u00e9es de WebRTC | Wildix\" \/>\n<meta property=\"og:description\" content=\"En d\u00e9ployant tr\u00e8s t\u00f4t des solutions WebRTC, Wildix a ouvert la voie \u00e0 l&#039;adoption par les UCC de cette technologie vitale et flexible. Aujourd&#039;hui, nous f\u00eatons nos 10 ans d&#039;utilisation.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.wildix.com\/fr\/celebration-10-annees-webrtc\/\" \/>\n<meta property=\"og:site_name\" content=\"Wildix\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/groups\/wildixtechwizards\/?mibextid=6NoCDW\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-30T09:40:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-19T10:24:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.wildix.com\/wp-content\/uploads\/2023\/05\/10-Years-of-WebRTC_2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Anna Zhuravlyova\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.wildix.com\/wp-content\/uploads\/2023\/05\/10-Years-of-WebRTC_2.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@wildix_\" \/>\n<meta name=\"twitter:site\" content=\"@wildix_\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Anna Zhuravlyova\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"10 ann\u00e9es de WebRTC | Wildix","description":"En d\u00e9ployant tr\u00e8s t\u00f4t des solutions WebRTC, Wildix a ouvert la voie \u00e0 l'adoption par les UCC de cette technologie vitale et flexible. Aujourd'hui, nous f\u00eatons nos 10 ans d'utilisation.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"10 ann\u00e9es de WebRTC | Wildix","og_description":"En d\u00e9ployant tr\u00e8s t\u00f4t des solutions WebRTC, Wildix a ouvert la voie \u00e0 l'adoption par les UCC de cette technologie vitale et flexible. Aujourd'hui, nous f\u00eatons nos 10 ans d'utilisation.","og_url":"https:\/\/www.wildix.com\/fr\/celebration-10-annees-webrtc\/","og_site_name":"Wildix","article_publisher":"https:\/\/www.facebook.com\/groups\/wildixtechwizards\/?mibextid=6NoCDW","article_published_time":"2023-05-30T09:40:39+00:00","article_modified_time":"2024-03-19T10:24:28+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.wildix.com\/wp-content\/uploads\/2023\/05\/10-Years-of-WebRTC_2.jpg","type":"image\/jpeg"}],"author":"Anna Zhuravlyova","twitter_card":"summary_large_image","twitter_image":"https:\/\/www.wildix.com\/wp-content\/uploads\/2023\/05\/10-Years-of-WebRTC_2.jpg","twitter_creator":"@wildix_","twitter_site":"@wildix_","twitter_misc":{"\u00c9crit par":"Anna Zhuravlyova","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.wildix.com\/fr\/celebration-10-annees-webrtc\/#article","isPartOf":{"@id":"https:\/\/www.wildix.com\/fr\/celebration-10-annees-webrtc\/"},"author":{"name":"Anna Zhuravlyova","@id":"https:\/\/www.wildix.com\/fr\/#\/schema\/person\/0175a2fef22d0be142fea01ed664ae39"},"headline":"Wildix c\u00e9l\u00e8bre les 10 ans du WebRTC","datePublished":"2023-05-30T09:40:39+00:00","dateModified":"2024-03-19T10:24:28+00:00","mainEntityOfPage":{"@id":"https:\/\/www.wildix.com\/fr\/celebration-10-annees-webrtc\/"},"wordCount":476,"publisher":{"@id":"https:\/\/www.wildix.com\/fr\/#organization"},"image":{"@id":"https:\/\/www.wildix.com\/fr\/celebration-10-annees-webrtc\/#primaryimage"},"thumbnailUrl":"https:\/\/www.wildix.com\/wp-content\/uploads\/2023\/05\/10-Years-of-WebRTC_2.webp","articleSection":["News FRA"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.wildix.com\/fr\/celebration-10-annees-webrtc\/","url":"https:\/\/www.wildix.com\/fr\/celebration-10-annees-webrtc\/","name":"10 ann\u00e9es de WebRTC | Wildix","isPartOf":{"@id":"https:\/\/www.wildix.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.wildix.com\/fr\/celebration-10-annees-webrtc\/#primaryimage"},"image":{"@id":"https:\/\/www.wildix.com\/fr\/celebration-10-annees-webrtc\/#primaryimage"},"thumbnailUrl":"https:\/\/www.wildix.com\/wp-content\/uploads\/2023\/05\/10-Years-of-WebRTC_2.webp","datePublished":"2023-05-30T09:40:39+00:00","dateModified":"2024-03-19T10:24:28+00:00","description":"En d\u00e9ployant tr\u00e8s t\u00f4t des solutions WebRTC, Wildix a ouvert la voie \u00e0 l'adoption par les UCC de cette technologie vitale et flexible. Aujourd'hui, nous f\u00eatons nos 10 ans d'utilisation.","breadcrumb":{"@id":"https:\/\/www.wildix.com\/fr\/celebration-10-annees-webrtc\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.wildix.com\/fr\/celebration-10-annees-webrtc\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.wildix.com\/fr\/celebration-10-annees-webrtc\/#primaryimage","url":"https:\/\/www.wildix.com\/wp-content\/uploads\/2023\/05\/10-Years-of-WebRTC_2.webp","contentUrl":"https:\/\/www.wildix.com\/wp-content\/uploads\/2023\/05\/10-Years-of-WebRTC_2.webp","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.wildix.com\/fr\/celebration-10-annees-webrtc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.wildix.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Wildix c\u00e9l\u00e8bre les 10 ans du WebRTC"}]},{"@type":"WebSite","@id":"https:\/\/www.wildix.com\/fr\/#website","url":"https:\/\/www.wildix.com\/fr\/","name":"Wildix","description":"","publisher":{"@id":"https:\/\/www.wildix.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.wildix.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.wildix.com\/fr\/#organization","name":"Wildix","url":"https:\/\/www.wildix.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.wildix.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.wildix.com\/wp-content\/uploads\/2021\/09\/logo-1.svg","contentUrl":"https:\/\/www.wildix.com\/wp-content\/uploads\/2021\/09\/logo-1.svg","caption":"Wildix"},"image":{"@id":"https:\/\/www.wildix.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/groups\/wildixtechwizards\/?mibextid=6NoCDW","https:\/\/x.com\/wildix_"]},{"@type":"Person","@id":"https:\/\/www.wildix.com\/fr\/#\/schema\/person\/0175a2fef22d0be142fea01ed664ae39","name":"Anna Zhuravlyova","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/cee65f8562e3ebd0a8e0b4431cfbd47801051b1e68ad6ab1ecff983d85f48715?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cee65f8562e3ebd0a8e0b4431cfbd47801051b1e68ad6ab1ecff983d85f48715?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cee65f8562e3ebd0a8e0b4431cfbd47801051b1e68ad6ab1ecff983d85f48715?s=96&d=mm&r=g","caption":"Anna Zhuravlyova"}}]}},"clean_content":"Communiqu\u00e9 de Presse Wildix c\u00e9l\u00e8bre les 10 ans du WebRTC Tallinn, Estonie \u2013 30 mai 2023 \u2013 Wildix est heureux de c\u00e9l\u00e9brer son 10e anniversaire avec le WebRTC. La technologie de communication dans le navigateur est essentielle pour les communications unifi\u00e9es modernes, et elle est maintenant largement adopt\u00e9e par les fournisseurs. L\u2019objectif du WebRTC \u00e9tait de mettre en \u0153uvre des communications en temps r\u00e9el \u00e0 travers plusieurs navigateurs, r\u00e9duisant ainsi le temps que les d\u00e9veloppeurs doivent consacrer \u00e0 la programmation. \u00c0 l\u2019instar du HTML et du texte qui sont devenus ouverts et accessibles \u00e0 tous, le WebRTC avait pour objectif de d\u00e9mocratiser la vid\u00e9o et la voix. \"Nous \u00e9tions convaincus que les communications unifi\u00e9es bas\u00e9es sur le web \u00e9taient la voie \u00e0 suivre, et notre premier client de communications unifi\u00e9es en 2009 \u00e9tait \u00e9galement enti\u00e8rement bas\u00e9 sur les technologies web\", a d\u00e9clar\u00e9 Dimitri Osler, CTO et fondateur de Wildix. \"Lorsque nous avons d\u00e9couvert le WebRTC, nous avons imm\u00e9diatement vu son potentiel et nous avons saut\u00e9 dans le train en marche pour cr\u00e9er des clients capables de l'utiliser. Dix ans plus tard, nous n'avons pas regard\u00e9 derri\u00e8re nous. Dimitri Osler, CTO et fondateur de Wildix Le WebRTC est l\u2019une des nombreuses technologies de base sur lesquelles reposent les services de Wildix, qui comprennent Collaboration, Wizyconf, Wizywebinar, x-bees, Kite et x-hoppers. Aujourd\u2019hui encore, Wildix est l\u2019un des rares services \u00e0 utiliser le WebRTC pour autre chose que le trunking, et beaucoup ne l\u2019utilisent que pour l\u2019audio. Avec les solutions Wildix, le WebRTC est m\u00eame utilis\u00e9 pour le contr\u00f4le d\u2019\u00e9cran \u00e0 distance, ce qui d\u00e9montre son potentiel. \u201cL\u2019utilisation du WebRTC signifie que nous n\u2019avons pas besoin de cr\u00e9er un client en dur, ce qui simplifie le d\u00e9ploiement sur plusieurs syst\u00e8mes\u201d, poursuit Dimitri. \u201cLa croissance du WebRTC et de Google Chrome permet \u00e0 nos solutions d\u2019\u00eatre adapt\u00e9es pour \u00eatre utilis\u00e9es dans une vari\u00e9t\u00e9 d\u2019environnements, et comme d\u2019autres navigateurs ont ajout\u00e9 la prise en charge, nous pourrions d\u00e9ployer sur ces navigateurs sans plugins ni API suppl\u00e9mentaires.\u201d Wildix compte aujourd\u2019hui plus d\u2019un million de d\u00e9ploiements bas\u00e9s sur le WebRTC, avec des utilisateurs finaux qui se connectent \u00e0 leurs clients, coll\u00e8gues et autres parties par le biais d\u2019engagements de navigateur \u00e0 navigateur et par l\u2019interm\u00e9diaire de liaisons SIP. \u201cLe WebRTC a explos\u00e9 en popularit\u00e9 et est devenu la norme qui facilite la connexion\u201d, note Dimitri. \u201cNous sommes fiers d\u2019avoir ouvert la voie et d\u2019avoir d\u00e9velopp\u00e9 cette solution en profondeur, et nous sommes reconnaissants \u00e0 tous ceux qui ont rendu cela possible.\u201d Pour plus d\u2019informations sur Wildix et nos solutions WebRTC, cliquez ici.","clean_excerpt":"Communiqu\u00e9 de Presse Wildix c\u00e9l\u00e8bre les 10 ans du WebRTC Tallinn, Estonie - 30 mai 2023 - Wildix est heureux de c\u00e9l\u00e9brer son 10e anniversaire avec le WebRTC. La technologie de communication dans le navigateur est essentielle pour les communications unifi\u00e9es modernes, et elle est maintenant largement adopt\u00e9e par les fournisseurs. L'objectif du WebRTC \u00e9tait...","_links":{"self":[{"href":"https:\/\/www.wildix.com\/fr\/wp-json\/wp\/v2\/posts\/8037886","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.wildix.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.wildix.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.wildix.com\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.wildix.com\/fr\/wp-json\/wp\/v2\/comments?post=8037886"}],"version-history":[{"count":3,"href":"https:\/\/www.wildix.com\/fr\/wp-json\/wp\/v2\/posts\/8037886\/revisions"}],"predecessor-version":[{"id":8079015,"href":"https:\/\/www.wildix.com\/fr\/wp-json\/wp\/v2\/posts\/8037886\/revisions\/8079015"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.wildix.com\/fr\/wp-json\/wp\/v2\/media\/8037817"}],"wp:attachment":[{"href":"https:\/\/www.wildix.com\/fr\/wp-json\/wp\/v2\/media?parent=8037886"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.wildix.com\/fr\/wp-json\/wp\/v2\/categories?post=8037886"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.wildix.com\/fr\/wp-json\/wp\/v2\/tags?post=8037886"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}