{"id":7934448,"date":"2022-06-09T05:29:43","date_gmt":"2022-06-09T03:29:43","guid":{"rendered":"https:\/\/www.wildix.com\/?post_type=case-studies&#038;p=7934448"},"modified":"2025-11-05T16:32:49","modified_gmt":"2025-11-05T15:32:49","slug":"la-facilitation-du-teletravail-grace-a-wildix-dans-un-ehpad","status":"publish","type":"case-studies","link":"https:\/\/www.wildix.com\/fr\/case-studies\/la-facilitation-du-teletravail-grace-a-wildix-dans-un-ehpad\/","title":{"rendered":"La facilitation du t\u00e9l\u00e9travail gr\u00e2ce \u00e0 Wildix dans un Ehpad"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"7934448\" class=\"elementor elementor-7934448 elementor-7928716\" data-elementor-post-type=\"case-studies\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fa876fc e-flex e-con-boxed e-con e-child\" data-id=\"fa876fc\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-36f15d6 elementor-widget elementor-widget-heading\" data-id=\"36f15d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Wildix et Etelys aident la Fondation Pauliani \u00e0 permettre le t\u00e9l\u00e9travail au sein de son EPHAD en modernisant son syst\u00e8me de communication d'entreprise, en pleine p\u00e9riode de confinement.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a424e4d elementor-widget elementor-widget-text-editor\" data-id=\"a424e4d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tWildix s&#8217;\u00e9vertue \u00e0\u00a0mettre \u00e0\u00a0dispositions des\u00a0solutions de\u00a0communications unifi\u00e9es, visant \u00e0\u00a0faciliter le travail et \u00e0\u00a0augmenter la\u00a0productivit\u00e9 des entreprises du monde entier. C&#8217;est \u00e9galement le cas des organismes \u00e0\u00a0but non lucratif qui se doivent de rester comp\u00e9titifs afin de maintenir un niveau de\u00a0service de\u00a0haute\u00a0qualit\u00e9.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e51a4ce elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"e51a4ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c8546b1 e-flex e-con-boxed e-con e-child\" data-id=\"c8546b1\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-ecdaf98 e-con-full e-flex e-con e-child\" data-id=\"ecdaf98\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cb6b4fd elementor-widget elementor-widget-image\" data-id=\"cb6b4fd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"100\" src=\"https:\/\/www.wildix.com\/wp-content\/uploads\/2022\/05\/foundation-pauliani.jpeg\" class=\"attachment-large size-large wp-image-7928735\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-30ef262 e-con-full e-flex e-con e-child\" data-id=\"30ef262\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3b2eb38 elementor-widget elementor-widget-text-editor\" data-id=\"3b2eb38\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tDepuis 1872, la\u00a0Fondation Pauliani est une \u0153uvre priv\u00e9e, de\u00a0type associatif et \u00e0\u00a0but non lucratif. Elle\u00a0g\u00e8re un\u00a0Ehpad, situ\u00e9 \u00e0\u00a0Nice, qui\u00a0offre \u00e0\u00a0ce jour une\u00a0capacit\u00e9 d&#8217;accueil de\u00a0214\u00a0lits.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3d7b326 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"3d7b326\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-17370f2 e-flex e-con-boxed e-con e-child\" data-id=\"17370f2\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0ccebb4 elementor-widget elementor-widget-text-editor\" data-id=\"0ccebb4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tWildix s&#8217;est donc entretenu avec C\u00e9dric Lacoste, Responsable\u00a0IT de\u00a0la\u00a0Fondation Pauliani, qui\u00a0poss\u00e8de une\u00a0solide exp\u00e9rience de\u00a0plus de\u00a020\u00a0ans dans les\u00a0\u00e9tablissements sanitaires et sociaux, le\u00a0service secr\u00e9tariat de\u00a0l&#8217;\u00e9tablissement, afin de recueillir leur retour d&#8217;exp\u00e9rience avec la\u00a0solution Wildix, 5\u00a0mois apr\u00e8s son\u00a0d\u00e9ploiement.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e00f15f elementor-widget elementor-widget-heading\" data-id=\"e00f15f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Le Probl\u00e8me<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ac865c8 elementor-widget elementor-widget-text-editor\" data-id=\"ac865c8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tC\u00e9dric Lacoste, Responsable\u00a0IT de\u00a0la\u00a0Fondation Pauliani, a\u00a0\u00e9t\u00e9 amen\u00e9 \u00e0\u00a0remplacer un\u00a0autocom qui\u00a0datait pour\u00a0ainsi dire de\u00a0la\u00a0cr\u00e9ation des\u00a0b\u00e2timents.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-15164ab elementor-widget elementor-widget-text-editor\" data-id=\"15164ab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<b>La situation \u00e9pid\u00e9mique de 2021 a \u00e9galement jou\u00e9 un r\u00f4le important dans la d\u00e9cision de C\u00e9dric Lacoste d&#8217;acc\u00e9l\u00e9rer la transition vers un nouveau syst\u00e8me de communications<\/b>. Il\u00a0a\u00a0fallu prendre un virage technologique commun \u00e0 de nombreuses autres entreprises\u00a0: celui du\u00a0t\u00e9l\u00e9travail.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-54cb9dd elementor-widget elementor-widget-text-editor\" data-id=\"54cb9dd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t&#8220;Avec la pand\u00e9mie de Covid\u201119, nous avons d\u00fb placer une partie de nos salari\u00e9s en t\u00e9l\u00e9travail. Cependant, les syst\u00e8mes que nous poss\u00e9dions auparavant ne nous permettaient pas de conserver une liaison t\u00e9l\u00e9phonique des postes des lignes de bureau \u00e0\u00a0leur\u00a0domicile&#8221;.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5a99923 elementor-widget elementor-widget-text-editor\" data-id=\"5a99923\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tLa Fondation Pauliani s&#8217;est alors mise \u00e0 la recherche d\u2019une solution r\u00e9pondant \u00e0 cette probl\u00e9matique, avec pour enjeux de faciliter le t\u00e9l\u00e9travail, en offrant des fonctionnalit\u00e9s modernes telles que la visioconf\u00e9rence avec les utilisateurs internes et externes, tout en facilitant la gestion de la t\u00e9l\u00e9phonie de\u00a0ses\u00a0r\u00e9sidents.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-770e3cf elementor-widget elementor-widget-text-editor\" data-id=\"770e3cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tEt\u00a0face \u00e0\u00a0l&#8217;urgence de la situation, l&#8217;utilisation de bons outils s&#8217;est alors av\u00e9r\u00e9e n\u00e9cessaire pour maintenir et optimiser la communication entre les membres du personnel de\u00a0la\u00a0Fondation.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6cb9aa8 elementor-widget elementor-widget-text-editor\" data-id=\"6cb9aa8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t&#8220;Les membres du personnel plac\u00e9s en t\u00e9l\u00e9travail se sont retrouv\u00e9s \u00e0\u00a0utiliser leur t\u00e9l\u00e9phone portable personnel car nous n&#8217;avions pas la possibilit\u00e9 d&#8217;externaliser nos lignes internes \u00e0 l&#8217;\u00e9tablissement chez les\u00a0utilisateurs&#8221;.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-33c5645 elementor-widget elementor-widget-image\" data-id=\"33c5645\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1200\" height=\"630\" src=\"https:\/\/www.wildix.com\/wp-content\/uploads\/2022\/05\/fondation-pauliani.jpeg\" class=\"attachment-full size-full wp-image-7928720\" alt=\"\" srcset=\"https:\/\/www.wildix.com\/wp-content\/uploads\/2022\/05\/fondation-pauliani.jpeg 1200w, https:\/\/www.wildix.com\/wp-content\/uploads\/2022\/05\/fondation-pauliani-300x158.jpeg 300w, https:\/\/www.wildix.com\/wp-content\/uploads\/2022\/05\/fondation-pauliani-1024x538.jpeg 1024w, https:\/\/www.wildix.com\/wp-content\/uploads\/2022\/05\/fondation-pauliani-768x403.jpeg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1520789 elementor-widget elementor-widget-heading\" data-id=\"1520789\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">La Solution<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0e37ca5 elementor-widget elementor-widget-text-editor\" data-id=\"0e37ca5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tContact\u00e9 dans un premier temps, l&#8217;ancien prestataire de t\u00e9l\u00e9phonie, Alcatel, proposait uniquement de retravailler sur l&#8217;ancien syst\u00e8me mais avec des modules ind\u00e9pendants les uns des autres, ce qui ne r\u00e9pondait pas aux attentes initiales. Plut\u00f4t que de passer par ce type d&#8217;installation, bien souvent source de panne et autres ennuis, la Fondation Pauliani s&#8217;est tourn\u00e9e vers la solution Wildix que C\u00e9dric Lacoste ne connaissait pas au d\u00e9part mais qui lui a rapidement \u00e9t\u00e9\u00a0recommand\u00e9e\u00a0:\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ba2cc94 elementor-widget elementor-widget-text-editor\" data-id=\"ba2cc94\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t&#8220;<b>Nous avons choisi Wildix sur les conseils d&#8217;Etelys partenaire Wildix<\/b>, un prestataire local, \u00e9galement bas\u00e9 \u00e0 Nice&#8221;, pr\u00e9cise t\u2011il, soulignant la r\u00e9activit\u00e9 d&#8217;Etelys dans le suivi du projet de refonte du syst\u00e8me de communication de l&#8217;Ehpad. Une expertise bienvenue qui a notamment permis la configuration de l&#8217;ensemble de la solution au syst\u00e8me d&#8217;appel malade d\u00e9j\u00e0 en place. &#8220;Nous nous sommes assur\u00e9s que le syst\u00e8me d&#8217;appel malade utilis\u00e9 par le client, en l&#8217;occurrence un syst\u00e8me Ackermann, soit bien interfac\u00e9 avec le syst\u00e8me Wildix&#8221;, pr\u00e9cise d&#8217;ailleurs David Cano, Dirigeant de la soci\u00e9t\u00e9\u00a0Etelys.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5058bfc elementor-widget elementor-widget-text-editor\" data-id=\"5058bfc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tUne fois les contours financiers de l&#8217;offre valid\u00e9s en interne, le d\u00e9ploiement a ainsi pu \u00eatre lanc\u00e9 dans les plus brefs d\u00e9lais. Un PBX local, adapt\u00e9 aux 350\u00a0lignes utilis\u00e9es \u00e0\u00a0l&#8217;\u00e9poque par\u00a0la\u00a0Fondation.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-23f12d9 elementor-widget elementor-widget-text-editor\" data-id=\"23f12d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t5 mois apr\u00e8s son d\u00e9ploiement, la solution Wildix a conquis ses utilisateurs, celle\u2011ci \u00e9tant aujourd&#8217;hui utilis\u00e9e par l&#8217;ensemble des \u00e9quipes de la Fondation dont le service Secr\u00e9tariat. Une prise en main &#8220;rapide, simple et efficace&#8221; comme nous l&#8217;un des membres du secr\u00e9tariat, qui nous explique qu&#8217;une fonctionnalit\u00e9 en particulier est tr\u00e8s appr\u00e9ci\u00e9e par l&#8217;\u00e9quipe\u00a0:\u00a0<b>l&#8217;acc\u00e8s au chat depuis son propre\u00a0t\u00e9l\u00e9phone<\/b>.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fa07e71 elementor-widget elementor-widget-text-editor\" data-id=\"fa07e71\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<b>&#8220;Lorsque les coll\u00e8gues sont en situation de t\u00e9l\u00e9travail, nous n&#8217;avons pas besoin de nous connecter sur leurs comptes pour suivre leur activit\u00e9, tout se fait en temps r\u00e9el, aussi bien par chat, que par messages vocaux. Nous avons m\u00eame cr\u00e9\u00e9 un chat de groupe qui nous permet d&#8217;\u00e9changer rapidement sur nos suivis. Nous retrouvons tout ce dont nous avons besoin sur l&#8217;application\u00a0mobile&#8221;.<\/b>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6b08a96 elementor-widget elementor-widget-text-editor\" data-id=\"6b08a96\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tC\u00e9dric Lacoste ajoute\u00a0: &#8220;Une belle fonctionnalit\u00e9 est\u00a0<b>la messagerie sur la bo\u00eete mail et la retranscription des messages vocaux<\/b>\u00a0qui nous facilite grandement le travail.\u00a0<b>Toutes ces petites choses de la solution Wildix mises bout \u00e0 bout constituent un vrai plus qui am\u00e9liore grandement notre\u00a0quotidien&#8221;<\/b>.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d4db6a8 elementor-widget elementor-widget-heading\" data-id=\"d4db6a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Les R\u00e9sultats<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fba71e8 elementor-widget elementor-widget-text-editor\" data-id=\"fba71e8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tAvec un syst\u00e8me permettant la cr\u00e9ation et l&#8217;attribution de lignes en toute simplicit\u00e9, la\u00a0Fondation Pauliani ma\u00eetrise dor\u00e9navant toutes ses communications de\u00a0A\u00a0\u00e0\u00a0Z.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-18034e6 elementor-widget elementor-widget-text-editor\" data-id=\"18034e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t&#8220;<b>Il n&#8217;y a clairement aucune comparaison possible avec notre ancien syst\u00e8me de t\u00e9l\u00e9phonie<\/b>, tant nous \u00e9tions sur de la t\u00e9l\u00e9phonie analogique \u00e0 100\u00a0% et ce syst\u00e8me ne pr\u00e9sentait aucune fonctionnalit\u00e9 int\u00e9ressante.&#8221; confirme C\u00e9dric Lacoste, qui souligne \u00e9galement\u00a0<b>la rapidit\u00e9 de traitement des demandes SAV par Etelys<\/b>\u00a0comme autre gros point de satisfaction. Au final, aujourd&#8217;hui ce ne sont\u00a0<b>pas moins de 380\u00a0licences qui ont \u00e9t\u00e9 ainsi activ\u00e9es<\/b>\u00a0dans l&#8217;Ehpad\u00a0ni\u00e7oise.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-773bab2 elementor-widget elementor-widget-text-editor\" data-id=\"773bab2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tUnanimes, nos deux utilisateurs affirment que\u00a0<b>la solution Wildix a bel et bien trouv\u00e9 sa place au c\u0153ur de\u00a0la\u00a0Fondation<\/b>\u00a0:\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-896f71c elementor-widget elementor-widget-text-editor\" data-id=\"896f71c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t&#8220;Nous recommandons la solution Wildix car\u00a0<b>que ce soit en administration ou pour les utilisateurs, tout se fait de fa\u00e7on tr\u00e8s simple. Chacun a la main mise sur l&#8217;outil pour communiquer sur sa disponibilit\u00e9 et son \u00e9tat de pr\u00e9sence<\/b>, ce qui garantit \u00e9galement\u00a0<b>une meilleure redistribution des appels<\/b>\u00a0pour les agents d&#8217;accueil du standard\u00a0t\u00e9l\u00e9phonique&#8221;.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2f8519a elementor-widget elementor-widget-text-editor\" data-id=\"2f8519a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tCar plut\u00f4t que d&#8217;opter pour des DECT en p\u00e9riode de confinement, le choix s&#8217;est naturellement port\u00e9 vers le\u00a0smartphone\u00a0:\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-284f831 elementor-widget elementor-widget-text-editor\" data-id=\"284f831\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<b>&#8220;La solution Wildix a permis de mettre en place le t\u00e9l\u00e9travail, notamment par le biais du chat<\/b>\u00a0qui a \u00e9t\u00e9 une r\u00e9elle d\u00e9couverte pour nous, et qui s&#8217;av\u00e8re tr\u00e8s utile, surtout quand les collaborateurs sont d\u00e9j\u00e0 en ligne.\u00a0<b>M\u00eame l&#8217;utilisation de notre t\u00e9l\u00e9phone personnel s&#8217;en est retrouv\u00e9e simplifi\u00e9e, ce qui \u00e9vite la multiplicit\u00e9 des outils. Nous sommes la g\u00e9n\u00e9ration mobile qui surfe toute la journ\u00e9e sur de nombreuses applications, et il faut avouer que pour le t\u00e9l\u00e9travail, l&#8217;application Wildix a \u00e9t\u00e9 un vrai plus. Nous avons diminu\u00e9 de moiti\u00e9 l&#8217;utilisation des t\u00e9l\u00e9phones physiques, tout passe aujourd&#8217;hui par l&#8217;interface Collaboration.&#8221;<\/b>\u00a0explique la responsable du\u00a0secr\u00e9tariat.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-896d791 elementor-widget elementor-widget-text-editor\" data-id=\"896d791\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tL&#8217;utilisation de l&#8217;interface Collaboration s&#8217;\u00e9tend \u00e9galement aux autres services, le BYOD (Bring Your Own Device) ainsi que le besoin limit\u00e9 en formation pour prendre en main l&#8217;outil, ayant facilit\u00e9 son acceptation, jusqu&#8217;\u00e0 remplacer dans certains cas l&#8217;utilisation du\u00a0t\u00e9l\u00e9phone de\u00a0bureau.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2804711 elementor-widget elementor-widget-text-editor\" data-id=\"2804711\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tC\u00e9dric Lacoste, non moins satisfait de la\u00a0couverture des besoins de l&#8217;Ehpad par la\u00a0solution Wildix\u00a0conclut\u00a0:\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ba3811 elementor-widget elementor-widget-text-editor\" data-id=\"2ba3811\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<b>&#8220;Aujourd&#8217;hui, nous sommes dans du Full\u00a0IP, tout est int\u00e9gr\u00e9 dans un seul syst\u00e8me. L&#8217;alliance de l&#8217;ergonomie et du c\u00f4t\u00e9 fonctionnel de Collaboration<\/b>\u00a0font que c&#8217;est un outil qui garantit une prise en main simple et efficace pour tous les employ\u00e9s qui b\u00e9n\u00e9ficient d\u00e9sormais d&#8217;une\u00a0<b>meilleure visualisation de l&#8217;activit\u00e9 de chacun en temps r\u00e9el<\/b>. Aujourd&#8217;hui, nous pouvons \u00e9galement b\u00e9n\u00e9ficier d&#8217;une\u00a0<b>tra\u00e7abilit\u00e9 des appels<\/b>, ce qui est une chose non n\u00e9gligeable dans un \u00e9tablissement de\u00a0soin&#8221;.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2625344 elementor-widget elementor-widget-text-editor\" data-id=\"2625344\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tUn client heureux qui a r\u00e9cemment renouvel\u00e9 sa confiance \u00e0 la solution Wildix et \u00e0 son partenaire Etelys, avec 40\u00a0nouvelles chambres et 10\u00a0nouveaux DECT envisag\u00e9s pour ses nouveaux b\u00e2timents et dont l&#8217;installation est pr\u00e9vue dans les semaines \u00e0 venir. Dans ces conditions, pourquoi alors changer une \u00e9quipe qui\u00a0gagne\u00a0?\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-13faec3 gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"13faec3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-1' class='gallery galleryid-7934448 gallery-columns-3 gallery-size-full'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"13faec3\" data-elementor-lightbox-title=\"la-fondation-pauliani-adopte-le-teletravail-avecwildix-1\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NzkyODc5NCwidXJsIjoiaHR0cHM6XC9cL3d3dy53aWxkaXguY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDIyXC8wNVwvbGEtZm9uZGF0aW9uLXBhdWxpYW5pLWFkb3B0ZS1sZS10ZWxldHJhdmFpbC1hdmVjd2lsZGl4LTEuanBlZyIsInNsaWRlc2hvdyI6IjEzZmFlYzMifQ%3D%3D\" href='https:\/\/www.wildix.com\/wp-content\/uploads\/2022\/05\/la-fondation-pauliani-adopte-le-teletravail-avecwildix-1.jpeg'><img decoding=\"async\" width=\"800\" height=\"532\" src=\"https:\/\/www.wildix.com\/wp-content\/uploads\/2022\/05\/la-fondation-pauliani-adopte-le-teletravail-avecwildix-1.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.wildix.com\/wp-content\/uploads\/2022\/05\/la-fondation-pauliani-adopte-le-teletravail-avecwildix-1.jpeg 800w, https:\/\/www.wildix.com\/wp-content\/uploads\/2022\/05\/la-fondation-pauliani-adopte-le-teletravail-avecwildix-1-300x200.jpeg 300w, https:\/\/www.wildix.com\/wp-content\/uploads\/2022\/05\/la-fondation-pauliani-adopte-le-teletravail-avecwildix-1-768x511.jpeg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"13faec3\" data-elementor-lightbox-title=\"la-fondation-pauliani-adopte-le-teletravail-avecwildix-2\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NzkyODgwMSwidXJsIjoiaHR0cHM6XC9cL3d3dy53aWxkaXguY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDIyXC8wNVwvbGEtZm9uZGF0aW9uLXBhdWxpYW5pLWFkb3B0ZS1sZS10ZWxldHJhdmFpbC1hdmVjd2lsZGl4LTIuanBlZyIsInNsaWRlc2hvdyI6IjEzZmFlYzMifQ%3D%3D\" href='https:\/\/www.wildix.com\/wp-content\/uploads\/2022\/05\/la-fondation-pauliani-adopte-le-teletravail-avecwildix-2.jpeg'><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"532\" src=\"https:\/\/www.wildix.com\/wp-content\/uploads\/2022\/05\/la-fondation-pauliani-adopte-le-teletravail-avecwildix-2.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.wildix.com\/wp-content\/uploads\/2022\/05\/la-fondation-pauliani-adopte-le-teletravail-avecwildix-2.jpeg 800w, https:\/\/www.wildix.com\/wp-content\/uploads\/2022\/05\/la-fondation-pauliani-adopte-le-teletravail-avecwildix-2-300x200.jpeg 300w, https:\/\/www.wildix.com\/wp-content\/uploads\/2022\/05\/la-fondation-pauliani-adopte-le-teletravail-avecwildix-2-768x511.jpeg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"13faec3\" data-elementor-lightbox-title=\"la-fondation-pauliani-adopte-le-teletravail-avecwildix-3\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NzkyODgwOCwidXJsIjoiaHR0cHM6XC9cL3d3dy53aWxkaXguY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDIyXC8wNVwvbGEtZm9uZGF0aW9uLXBhdWxpYW5pLWFkb3B0ZS1sZS10ZWxldHJhdmFpbC1hdmVjd2lsZGl4LTMuanBlZyIsInNsaWRlc2hvdyI6IjEzZmFlYzMifQ%3D%3D\" href='https:\/\/www.wildix.com\/wp-content\/uploads\/2022\/05\/la-fondation-pauliani-adopte-le-teletravail-avecwildix-3.jpeg'><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"532\" src=\"https:\/\/www.wildix.com\/wp-content\/uploads\/2022\/05\/la-fondation-pauliani-adopte-le-teletravail-avecwildix-3.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.wildix.com\/wp-content\/uploads\/2022\/05\/la-fondation-pauliani-adopte-le-teletravail-avecwildix-3.jpeg 800w, https:\/\/www.wildix.com\/wp-content\/uploads\/2022\/05\/la-fondation-pauliani-adopte-le-teletravail-avecwildix-3-300x200.jpeg 300w, https:\/\/www.wildix.com\/wp-content\/uploads\/2022\/05\/la-fondation-pauliani-adopte-le-teletravail-avecwildix-3-768x511.jpeg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d87cbde e-flex e-con-boxed e-con e-child\" data-id=\"d87cbde\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-393313b elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"393313b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1a5d59f elementor-widget elementor-widget-heading\" data-id=\"1a5d59f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">La solution a \u00e9t\u00e9 fournie par le\u00a0partenaire\u00a0Wildix<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-40aff6c e-con-full e-flex e-con e-child\" data-id=\"40aff6c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t<div class=\"elementor-element elementor-element-1db4c08 e-con-full e-flex e-con e-child\" data-id=\"1db4c08\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b9371fc elementor-widget elementor-widget-image\" data-id=\"b9371fc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"120\" src=\"https:\/\/www.wildix.com\/wp-content\/uploads\/2022\/05\/etelys-golden-wildix-partner.jpeg\" class=\"attachment-large size-large wp-image-7928821\" alt=\"\" srcset=\"https:\/\/www.wildix.com\/wp-content\/uploads\/2022\/05\/etelys-golden-wildix-partner.jpeg 370w, https:\/\/www.wildix.com\/wp-content\/uploads\/2022\/05\/etelys-golden-wildix-partner-300x97.jpeg 300w\" sizes=\"(max-width: 370px) 100vw, 370px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-09a9a15 e-con-full e-flex e-con e-child\" data-id=\"09a9a15\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-94458e4 elementor-align-start elementor-tablet-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"94458e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-city\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M616 192H480V24c0-13.26-10.74-24-24-24H312c-13.26 0-24 10.74-24 24v72h-64V16c0-8.84-7.16-16-16-16h-16c-8.84 0-16 7.16-16 16v80h-64V16c0-8.84-7.16-16-16-16H80c-8.84 0-16 7.16-16 16v80H24c-13.26 0-24 10.74-24 24v360c0 17.67 14.33 32 32 32h576c17.67 0 32-14.33 32-32V216c0-13.26-10.75-24-24-24zM128 404c0 6.63-5.37 12-12 12H76c-6.63 0-12-5.37-12-12v-40c0-6.63 5.37-12 12-12h40c6.63 0 12 5.37 12 12v40zm0-96c0 6.63-5.37 12-12 12H76c-6.63 0-12-5.37-12-12v-40c0-6.63 5.37-12 12-12h40c6.63 0 12 5.37 12 12v40zm0-96c0 6.63-5.37 12-12 12H76c-6.63 0-12-5.37-12-12v-40c0-6.63 5.37-12 12-12h40c6.63 0 12 5.37 12 12v40zm128 192c0 6.63-5.37 12-12 12h-40c-6.63 0-12-5.37-12-12v-40c0-6.63 5.37-12 12-12h40c6.63 0 12 5.37 12 12v40zm0-96c0 6.63-5.37 12-12 12h-40c-6.63 0-12-5.37-12-12v-40c0-6.63 5.37-12 12-12h40c6.63 0 12 5.37 12 12v40zm0-96c0 6.63-5.37 12-12 12h-40c-6.63 0-12-5.37-12-12v-40c0-6.63 5.37-12 12-12h40c6.63 0 12 5.37 12 12v40zm160 96c0 6.63-5.37 12-12 12h-40c-6.63 0-12-5.37-12-12v-40c0-6.63 5.37-12 12-12h40c6.63 0 12 5.37 12 12v40zm0-96c0 6.63-5.37 12-12 12h-40c-6.63 0-12-5.37-12-12v-40c0-6.63 5.37-12 12-12h40c6.63 0 12 5.37 12 12v40zm0-96c0 6.63-5.37 12-12 12h-40c-6.63 0-12-5.37-12-12V76c0-6.63 5.37-12 12-12h40c6.63 0 12 5.37 12 12v40zm160 288c0 6.63-5.37 12-12 12h-40c-6.63 0-12-5.37-12-12v-40c0-6.63 5.37-12 12-12h40c6.63 0 12 5.37 12 12v40zm0-96c0 6.63-5.37 12-12 12h-40c-6.63 0-12-5.37-12-12v-40c0-6.63 5.37-12 12-12h40c6.63 0 12 5.37 12 12v40z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">ETELYS<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-map-marker-alt\" viewBox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M172.268 501.67C26.97 291.031 0 269.413 0 192 0 85.961 85.961 0 192 0s192 85.961 192 192c0 77.413-26.97 99.031-172.268 309.67-9.535 13.774-29.93 13.773-39.464 0zM192 272c44.183 0 80-35.817 80-80s-35.817-80-80-80-80 35.817-80 80 35.817 80 80 80z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">141\u00a0Promenade\u00a0des\u00a0Anglais, 06200\u00a0Nice,\u00a0France<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"mailto:adv@etelys.fr\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-envelope\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M502.3 190.8c3.9-3.1 9.7-.2 9.7 4.7V400c0 26.5-21.5 48-48 48H48c-26.5 0-48-21.5-48-48V195.6c0-5 5.7-7.8 9.7-4.7 22.4 17.4 52.1 39.5 154.1 113.6 21.1 15.4 56.7 47.8 92.2 47.6 35.7.3 72-32.8 92.3-47.6 102-74.1 131.6-96.3 154-113.7zM256 320c23.2.4 56.6-29.2 73.4-41.4 132.7-96.3 142.8-104.7 173.4-128.7 5.8-4.5 9.2-11.5 9.2-18.9v-19c0-26.5-21.5-48-48-48H48C21.5 64 0 85.5 0 112v19c0 7.4 3.4 14.3 9.2 18.9 30.6 23.9 40.7 32.4 173.4 128.7 16.8 12.2 50.2 41.8 73.4 41.4z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">adv@etelys.fr<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"tel:+33493861596\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-phone-alt\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M497.39 361.8l-112-48a24 24 0 0 0-28 6.9l-49.6 60.6A370.66 370.66 0 0 1 130.6 204.11l60.6-49.6a23.94 23.94 0 0 0 6.9-28l-48-112A24.16 24.16 0 0 0 122.6.61l-104 24A24 24 0 0 0 0 48c0 256.5 207.9 464 464 464a24 24 0 0 0 23.4-18.6l24-104a24.29 24.29 0 0 0-14.01-27.6z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">+33 (493) 86 15 96<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/etelys.fr\/\" target=\"_blank\" rel=\"nofollow\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-globe-americas\" viewBox=\"0 0 496 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M248 8C111.03 8 0 119.03 0 256s111.03 248 248 248 248-111.03 248-248S384.97 8 248 8zm82.29 357.6c-3.9 3.88-7.99 7.95-11.31 11.28-2.99 3-5.1 6.7-6.17 10.71-1.51 5.66-2.73 11.38-4.77 16.87l-17.39 46.85c-13.76 3-28 4.69-42.65 4.69v-27.38c1.69-12.62-7.64-36.26-22.63-51.25-6-6-9.37-14.14-9.37-22.63v-32.01c0-11.64-6.27-22.34-16.46-27.97-14.37-7.95-34.81-19.06-48.81-26.11-11.48-5.78-22.1-13.14-31.65-21.75l-.8-.72a114.792 114.792 0 0 1-18.06-20.74c-9.38-13.77-24.66-36.42-34.59-51.14 20.47-45.5 57.36-82.04 103.2-101.89l24.01 12.01C203.48 89.74 216 82.01 216 70.11v-11.3c7.99-1.29 16.12-2.11 24.39-2.42l28.3 28.3c6.25 6.25 6.25 16.38 0 22.63L264 112l-10.34 10.34c-3.12 3.12-3.12 8.19 0 11.31l4.69 4.69c3.12 3.12 3.12 8.19 0 11.31l-8 8a8.008 8.008 0 0 1-5.66 2.34h-8.99c-2.08 0-4.08.81-5.58 2.27l-9.92 9.65a8.008 8.008 0 0 0-1.58 9.31l15.59 31.19c2.66 5.32-1.21 11.58-7.15 11.58h-5.64c-1.93 0-3.79-.7-5.24-1.96l-9.28-8.06a16.017 16.017 0 0 0-15.55-3.1l-31.17 10.39a11.95 11.95 0 0 0-8.17 11.34c0 4.53 2.56 8.66 6.61 10.69l11.08 5.54c9.41 4.71 19.79 7.16 30.31 7.16s22.59 27.29 32 32h66.75c8.49 0 16.62 3.37 22.63 9.37l13.69 13.69a30.503 30.503 0 0 1 8.93 21.57 46.536 46.536 0 0 1-13.72 32.98zM417 274.25c-5.79-1.45-10.84-5-14.15-9.97l-17.98-26.97a23.97 23.97 0 0 1 0-26.62l19.59-29.38c2.32-3.47 5.5-6.29 9.24-8.15l12.98-6.49C440.2 193.59 448 223.87 448 256c0 8.67-.74 17.16-1.82 25.54L417 274.25z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">etelys.fr<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9272eab elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"9272eab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Wildix et Etelys aident la Fondation Pauliani \u00e0 permettre le t\u00e9l\u00e9travail au sein de son EPHAD en modernisant son syst\u00e8me de communication d&#8217;entreprise, en pleine p\u00e9riode de confinement. Wildix s&#8217;\u00e9vertue \u00e0\u00a0mettre \u00e0\u00a0dispositions des\u00a0solutions de\u00a0communications unifi\u00e9es, visant \u00e0\u00a0faciliter le travail et \u00e0\u00a0augmenter la\u00a0productivit\u00e9 des entreprises du monde entier. C&#8217;est \u00e9galement le cas des organismes \u00e0\u00a0but non [&hellip;]<\/p>\n","protected":false},"featured_media":7906060,"template":"","meta":{"_acf_changed":false,"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"full-width-container","site-content-style":"unboxed","site-sidebar-style":"unboxed","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_jet_sm_ready_style":"","_jet_sm_style":"","_jet_sm_controls_values":"","_jet_sm_fonts_collection":"","_jet_sm_fonts_links":"","footnotes":""},"case_study_industry":[878],"case_study_region":[928],"case_study_size":[922],"class_list":["post-7934448","case-studies","type-case-studies","status-publish","has-post-thumbnail","hentry","case_study_industry-social-public-services-fr","case_study_region-french-speaking-countries-fr","case_study_size-250-500-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La facilitation du t\u00e9l\u00e9travail gr\u00e2ce \u00e0 Wildix dans un Ehpad | Wildix<\/title>\n<meta name=\"description\" content=\"Wildix et Etelys aident la Fondation Pauliani \u00e0 adopter le t\u00e9l\u00e9travail dans son EPHAD en modernisant son syst\u00e8me de communication d&#039;entreprise en pleine p\u00e9riode de confinement.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La facilitation du t\u00e9l\u00e9travail gr\u00e2ce \u00e0 Wildix dans un Ehpad | Wildix\" \/>\n<meta property=\"og:description\" content=\"Wildix et Etelys aident la Fondation Pauliani \u00e0 adopter le t\u00e9l\u00e9travail dans son EPHAD en modernisant son syst\u00e8me de communication d&#039;entreprise en pleine p\u00e9riode de confinement.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.wildix.com\/fr\/case-studies\/la-facilitation-du-teletravail-grace-a-wildix-dans-un-ehpad\/\" \/>\n<meta property=\"og:site_name\" content=\"Wildix\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/groups\/wildixtechwizards\/?mibextid=6NoCDW\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-05T15:32:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.wildix.com\/wp-content\/uploads\/2022\/04\/fondation-pauliani.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@wildix_\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La facilitation du t\u00e9l\u00e9travail gr\u00e2ce \u00e0 Wildix dans un Ehpad | Wildix","description":"Wildix et Etelys aident la Fondation Pauliani \u00e0 adopter le t\u00e9l\u00e9travail dans son EPHAD en modernisant son syst\u00e8me de communication d'entreprise en pleine p\u00e9riode de confinement.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"La facilitation du t\u00e9l\u00e9travail gr\u00e2ce \u00e0 Wildix dans un Ehpad | Wildix","og_description":"Wildix et Etelys aident la Fondation Pauliani \u00e0 adopter le t\u00e9l\u00e9travail dans son EPHAD en modernisant son syst\u00e8me de communication d'entreprise en pleine p\u00e9riode de confinement.","og_url":"https:\/\/www.wildix.com\/fr\/case-studies\/la-facilitation-du-teletravail-grace-a-wildix-dans-un-ehpad\/","og_site_name":"Wildix","article_publisher":"https:\/\/www.facebook.com\/groups\/wildixtechwizards\/?mibextid=6NoCDW","article_modified_time":"2025-11-05T15:32:49+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.wildix.com\/wp-content\/uploads\/2022\/04\/fondation-pauliani.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@wildix_","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.wildix.com\/fr\/case-studies\/la-facilitation-du-teletravail-grace-a-wildix-dans-un-ehpad\/","url":"https:\/\/www.wildix.com\/fr\/case-studies\/la-facilitation-du-teletravail-grace-a-wildix-dans-un-ehpad\/","name":"La facilitation du t\u00e9l\u00e9travail gr\u00e2ce \u00e0 Wildix dans un Ehpad | Wildix","isPartOf":{"@id":"https:\/\/www.wildix.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.wildix.com\/fr\/case-studies\/la-facilitation-du-teletravail-grace-a-wildix-dans-un-ehpad\/#primaryimage"},"image":{"@id":"https:\/\/www.wildix.com\/fr\/case-studies\/la-facilitation-du-teletravail-grace-a-wildix-dans-un-ehpad\/#primaryimage"},"thumbnailUrl":"https:\/\/www.wildix.com\/wp-content\/uploads\/2022\/04\/fondation-pauliani.jpg","datePublished":"2022-06-09T03:29:43+00:00","dateModified":"2025-11-05T15:32:49+00:00","description":"Wildix et Etelys aident la Fondation Pauliani \u00e0 adopter le t\u00e9l\u00e9travail dans son EPHAD en modernisant son syst\u00e8me de communication d'entreprise en pleine p\u00e9riode de confinement.","breadcrumb":{"@id":"https:\/\/www.wildix.com\/fr\/case-studies\/la-facilitation-du-teletravail-grace-a-wildix-dans-un-ehpad\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.wildix.com\/fr\/case-studies\/la-facilitation-du-teletravail-grace-a-wildix-dans-un-ehpad\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.wildix.com\/fr\/case-studies\/la-facilitation-du-teletravail-grace-a-wildix-dans-un-ehpad\/#primaryimage","url":"https:\/\/www.wildix.com\/wp-content\/uploads\/2022\/04\/fondation-pauliani.jpg","contentUrl":"https:\/\/www.wildix.com\/wp-content\/uploads\/2022\/04\/fondation-pauliani.jpg","width":1200,"height":630,"caption":"Fondation Pauliani - Case study"},{"@type":"BreadcrumbList","@id":"https:\/\/www.wildix.com\/fr\/case-studies\/la-facilitation-du-teletravail-grace-a-wildix-dans-un-ehpad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.wildix.com\/fr\/home-copy\/"},{"@type":"ListItem","position":2,"name":"Case Studies","item":"https:\/\/www.wildix.com\/fr\/case-studies\/"},{"@type":"ListItem","position":3,"name":"La facilitation du t\u00e9l\u00e9travail gr\u00e2ce \u00e0 Wildix dans un Ehpad"}]},{"@type":"WebSite","@id":"https:\/\/www.wildix.com\/fr\/#website","url":"https:\/\/www.wildix.com\/fr\/","name":"Wildix","description":"","publisher":{"@id":"https:\/\/www.wildix.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.wildix.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.wildix.com\/fr\/#organization","name":"Wildix","url":"https:\/\/www.wildix.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.wildix.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.wildix.com\/wp-content\/uploads\/2021\/09\/logo-1.svg","contentUrl":"https:\/\/www.wildix.com\/wp-content\/uploads\/2021\/09\/logo-1.svg","caption":"Wildix"},"image":{"@id":"https:\/\/www.wildix.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/groups\/wildixtechwizards\/?mibextid=6NoCDW","https:\/\/x.com\/wildix_"]}]}},"clean_content":"Wildix et Etelys aident la Fondation Pauliani \u00e0 permettre le t\u00e9l\u00e9travail au sein de son EPHAD en modernisant son syst\u00e8me de communication d'entreprise, en pleine p\u00e9riode de confinement. Wildix s\u2019\u00e9vertue \u00e0\u00a0mettre \u00e0\u00a0dispositions des\u00a0solutions de\u00a0communications unifi\u00e9es, visant \u00e0\u00a0faciliter le travail et \u00e0\u00a0augmenter la\u00a0productivit\u00e9 des entreprises du monde entier. C\u2019est \u00e9galement le cas des organismes \u00e0\u00a0but non lucratif qui se doivent de rester comp\u00e9titifs afin de maintenir un niveau de\u00a0service de\u00a0haute\u00a0qualit\u00e9. Depuis 1872, la\u00a0Fondation Pauliani est une \u0153uvre priv\u00e9e, de\u00a0type associatif et \u00e0\u00a0but non lucratif. Elle\u00a0g\u00e8re un\u00a0Ehpad, situ\u00e9 \u00e0\u00a0Nice, qui\u00a0offre \u00e0\u00a0ce jour une\u00a0capacit\u00e9 d\u2019accueil de\u00a0214\u00a0lits. Wildix s\u2019est donc entretenu avec C\u00e9dric Lacoste, Responsable\u00a0IT de\u00a0la\u00a0Fondation Pauliani, qui\u00a0poss\u00e8de une\u00a0solide exp\u00e9rience de\u00a0plus de\u00a020\u00a0ans dans les\u00a0\u00e9tablissements sanitaires et sociaux, le\u00a0service secr\u00e9tariat de\u00a0l\u2019\u00e9tablissement, afin de recueillir leur retour d\u2019exp\u00e9rience avec la\u00a0solution Wildix, 5\u00a0mois apr\u00e8s son\u00a0d\u00e9ploiement. Le Probl\u00e8me C\u00e9dric Lacoste, Responsable\u00a0IT de\u00a0la\u00a0Fondation Pauliani, a\u00a0\u00e9t\u00e9 amen\u00e9 \u00e0\u00a0remplacer un\u00a0autocom qui\u00a0datait pour\u00a0ainsi dire de\u00a0la\u00a0cr\u00e9ation des\u00a0b\u00e2timents. La situation \u00e9pid\u00e9mique de 2021 a \u00e9galement jou\u00e9 un r\u00f4le important dans la d\u00e9cision de C\u00e9dric Lacoste d\u2019acc\u00e9l\u00e9rer la transition vers un nouveau syst\u00e8me de communications. Il\u00a0a\u00a0fallu prendre un virage technologique commun \u00e0 de nombreuses autres entreprises\u00a0: celui du\u00a0t\u00e9l\u00e9travail. \u201cAvec la pand\u00e9mie de Covid\u201119, nous avons d\u00fb placer une partie de nos salari\u00e9s en t\u00e9l\u00e9travail. Cependant, les syst\u00e8mes que nous poss\u00e9dions auparavant ne nous permettaient pas de conserver une liaison t\u00e9l\u00e9phonique des postes des lignes de bureau \u00e0\u00a0leur\u00a0domicile\u201d. La Fondation Pauliani s\u2019est alors mise \u00e0 la recherche d\u2019une solution r\u00e9pondant \u00e0 cette probl\u00e9matique, avec pour enjeux de faciliter le t\u00e9l\u00e9travail, en offrant des fonctionnalit\u00e9s modernes telles que la visioconf\u00e9rence avec les utilisateurs internes et externes, tout en facilitant la gestion de la t\u00e9l\u00e9phonie de\u00a0ses\u00a0r\u00e9sidents. Et\u00a0face \u00e0\u00a0l\u2019urgence de la situation, l\u2019utilisation de bons outils s\u2019est alors av\u00e9r\u00e9e n\u00e9cessaire pour maintenir et optimiser la communication entre les membres du personnel de\u00a0la\u00a0Fondation. \u201cLes membres du personnel plac\u00e9s en t\u00e9l\u00e9travail se sont retrouv\u00e9s \u00e0\u00a0utiliser leur t\u00e9l\u00e9phone portable personnel car nous n\u2019avions pas la possibilit\u00e9 d\u2019externaliser nos lignes internes \u00e0 l\u2019\u00e9tablissement chez les\u00a0utilisateurs\u201d. La Solution Contact\u00e9 dans un premier temps, l\u2019ancien prestataire de t\u00e9l\u00e9phonie, Alcatel, proposait uniquement de retravailler sur l\u2019ancien syst\u00e8me mais avec des modules ind\u00e9pendants les uns des autres, ce qui ne r\u00e9pondait pas aux attentes initiales. Plut\u00f4t que de passer par ce type d\u2019installation, bien souvent source de panne et autres ennuis, la Fondation Pauliani s\u2019est tourn\u00e9e vers la solution Wildix que C\u00e9dric Lacoste ne connaissait pas au d\u00e9part mais qui lui a rapidement \u00e9t\u00e9\u00a0recommand\u00e9e\u00a0: \u201cNous avons choisi Wildix sur les conseils d\u2019Etelys partenaire Wildix, un prestataire local, \u00e9galement bas\u00e9 \u00e0 Nice\u201d, pr\u00e9cise t\u2011il, soulignant la r\u00e9activit\u00e9 d\u2019Etelys dans le suivi du projet de refonte du syst\u00e8me de communication de l\u2019Ehpad. Une expertise bienvenue qui a notamment permis la configuration de l\u2019ensemble de la solution au syst\u00e8me d\u2019appel malade d\u00e9j\u00e0 en place. \u201cNous nous sommes assur\u00e9s que le syst\u00e8me d\u2019appel malade utilis\u00e9 par le client, en l\u2019occurrence un syst\u00e8me Ackermann, soit bien interfac\u00e9 avec le syst\u00e8me Wildix\u201d, pr\u00e9cise d\u2019ailleurs David Cano, Dirigeant de la soci\u00e9t\u00e9\u00a0Etelys. Une fois les contours financiers de l\u2019offre valid\u00e9s en interne, le d\u00e9ploiement a ainsi pu \u00eatre lanc\u00e9 dans les plus brefs d\u00e9lais. Un PBX local, adapt\u00e9 aux 350\u00a0lignes utilis\u00e9es \u00e0\u00a0l\u2019\u00e9poque par\u00a0la\u00a0Fondation. 5 mois apr\u00e8s son d\u00e9ploiement, la solution Wildix a conquis ses utilisateurs, celle\u2011ci \u00e9tant aujourd\u2019hui utilis\u00e9e par l\u2019ensemble des \u00e9quipes de la Fondation dont le service Secr\u00e9tariat. Une prise en main \u201crapide, simple et efficace\u201d comme nous l\u2019un des membres du secr\u00e9tariat, qui nous explique qu\u2019une fonctionnalit\u00e9 en particulier est tr\u00e8s appr\u00e9ci\u00e9e par l\u2019\u00e9quipe\u00a0:\u00a0l\u2019acc\u00e8s au chat depuis son propre\u00a0t\u00e9l\u00e9phone. \u201cLorsque les coll\u00e8gues sont en situation de t\u00e9l\u00e9travail, nous n\u2019avons pas besoin de nous connecter sur leurs comptes pour suivre leur activit\u00e9, tout se fait en temps r\u00e9el, aussi bien par chat, que par messages vocaux. Nous avons m\u00eame cr\u00e9\u00e9 un chat de groupe qui nous permet d\u2019\u00e9changer rapidement sur nos suivis. Nous retrouvons tout ce dont nous avons besoin sur l\u2019application\u00a0mobile\u201d. C\u00e9dric Lacoste ajoute\u00a0: \u201cUne belle fonctionnalit\u00e9 est\u00a0la messagerie sur la bo\u00eete mail et la retranscription des messages vocaux\u00a0qui nous facilite grandement le travail.\u00a0Toutes ces petites choses de la solution Wildix mises bout \u00e0 bout constituent un vrai plus qui am\u00e9liore grandement notre\u00a0quotidien\u201d. Les R\u00e9sultats Avec un syst\u00e8me permettant la cr\u00e9ation et l\u2019attribution de lignes en toute simplicit\u00e9, la\u00a0Fondation Pauliani ma\u00eetrise dor\u00e9navant toutes ses communications de\u00a0A\u00a0\u00e0\u00a0Z. \u201cIl n\u2019y a clairement aucune comparaison possible avec notre ancien syst\u00e8me de t\u00e9l\u00e9phonie, tant nous \u00e9tions sur de la t\u00e9l\u00e9phonie analogique \u00e0 100\u00a0% et ce syst\u00e8me ne pr\u00e9sentait aucune fonctionnalit\u00e9 int\u00e9ressante.\u201d confirme C\u00e9dric Lacoste, qui souligne \u00e9galement\u00a0la rapidit\u00e9 de traitement des demandes SAV par Etelys\u00a0comme autre gros point de satisfaction. Au final, aujourd\u2019hui ce ne sont\u00a0pas moins de 380\u00a0licences qui ont \u00e9t\u00e9 ainsi activ\u00e9es\u00a0dans l\u2019Ehpad\u00a0ni\u00e7oise. Unanimes, nos deux utilisateurs affirment que\u00a0la solution Wildix a bel et bien trouv\u00e9 sa place au c\u0153ur de\u00a0la\u00a0Fondation\u00a0: \u201cNous recommandons la solution Wildix car\u00a0que ce soit en administration ou pour les utilisateurs, tout se fait de fa\u00e7on tr\u00e8s simple. Chacun a la main mise sur l\u2019outil pour communiquer sur sa disponibilit\u00e9 et son \u00e9tat de pr\u00e9sence, ce qui garantit \u00e9galement\u00a0une meilleure redistribution des appels\u00a0pour les agents d\u2019accueil du standard\u00a0t\u00e9l\u00e9phonique\u201d. Car plut\u00f4t que d\u2019opter pour des DECT en p\u00e9riode de confinement, le choix s\u2019est naturellement port\u00e9 vers le\u00a0smartphone\u00a0: \u201cLa solution Wildix a permis de mettre en place le t\u00e9l\u00e9travail, notamment par le biais du chat\u00a0qui a \u00e9t\u00e9 une r\u00e9elle d\u00e9couverte pour nous, et qui s\u2019av\u00e8re tr\u00e8s utile, surtout quand les collaborateurs sont d\u00e9j\u00e0 en ligne.\u00a0M\u00eame l\u2019utilisation de notre t\u00e9l\u00e9phone personnel s\u2019en est retrouv\u00e9e simplifi\u00e9e, ce qui \u00e9vite la multiplicit\u00e9 des outils. Nous sommes la g\u00e9n\u00e9ration mobile qui surfe toute la journ\u00e9e sur de nombreuses applications, et il faut avouer que pour le t\u00e9l\u00e9travail, l\u2019application Wildix a \u00e9t\u00e9 un vrai plus. Nous avons diminu\u00e9 de moiti\u00e9 l\u2019utilisation des t\u00e9l\u00e9phones physiques, tout passe aujourd\u2019hui par l\u2019interface Collaboration.\u201d\u00a0explique la responsable du\u00a0secr\u00e9tariat. L\u2019utilisation de l\u2019interface Collaboration s\u2019\u00e9tend \u00e9galement aux autres services, le BYOD (Bring Your Own Device) ainsi que le besoin limit\u00e9 en formation pour prendre en main l\u2019outil, ayant facilit\u00e9 son acceptation, jusqu\u2019\u00e0 remplacer dans certains cas l\u2019utilisation du\u00a0t\u00e9l\u00e9phone de\u00a0bureau. C\u00e9dric Lacoste, non moins satisfait de la\u00a0couverture des besoins de l\u2019Ehpad par la\u00a0solution Wildix\u00a0conclut\u00a0: \u201cAujourd\u2019hui, nous sommes dans du Full\u00a0IP, tout est int\u00e9gr\u00e9 dans un seul syst\u00e8me. L\u2019alliance de l\u2019ergonomie et du c\u00f4t\u00e9 fonctionnel de Collaboration\u00a0font que c\u2019est un outil qui garantit une prise en main simple et efficace pour tous les employ\u00e9s qui b\u00e9n\u00e9ficient d\u00e9sormais d\u2019une\u00a0meilleure visualisation de l\u2019activit\u00e9 de chacun en temps r\u00e9el. Aujourd\u2019hui, nous pouvons \u00e9galement b\u00e9n\u00e9ficier d\u2019une\u00a0tra\u00e7abilit\u00e9 des appels, ce qui est une chose non n\u00e9gligeable dans un \u00e9tablissement de\u00a0soin\u201d. Un client heureux qui a r\u00e9cemment renouvel\u00e9 sa confiance \u00e0 la solution Wildix et \u00e0 son partenaire Etelys, avec 40\u00a0nouvelles chambres et 10\u00a0nouveaux DECT envisag\u00e9s pour ses nouveaux b\u00e2timents et dont l\u2019installation est pr\u00e9vue dans les semaines \u00e0 venir. Dans ces conditions, pourquoi alors changer une \u00e9quipe qui\u00a0gagne\u00a0? La solution a \u00e9t\u00e9 fournie par le\u00a0partenaire\u00a0Wildix ETELYS 141\u00a0Promenade\u00a0des\u00a0Anglais, 06200\u00a0Nice,\u00a0France adv@etelys.fr +33 (493) 86 15 96 etelys.fr","clean_excerpt":"Wildix et Etelys aident la Fondation Pauliani \u00e0 permettre le t\u00e9l\u00e9travail au sein de son EPHAD en modernisant son syst\u00e8me de communication d'entreprise, en pleine p\u00e9riode de confinement. Wildix s'\u00e9vertue \u00e0\u00a0mettre \u00e0\u00a0dispositions des\u00a0solutions de\u00a0communications unifi\u00e9es, visant \u00e0\u00a0faciliter le travail et \u00e0\u00a0augmenter la\u00a0productivit\u00e9 des entreprises du monde entier. C'est \u00e9galement le cas des organismes \u00e0\u00a0but non...","_links":{"self":[{"href":"https:\/\/www.wildix.com\/fr\/wp-json\/wp\/v2\/case-studies\/7934448","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.wildix.com\/fr\/wp-json\/wp\/v2\/case-studies"}],"about":[{"href":"https:\/\/www.wildix.com\/fr\/wp-json\/wp\/v2\/types\/case-studies"}],"version-history":[{"count":5,"href":"https:\/\/www.wildix.com\/fr\/wp-json\/wp\/v2\/case-studies\/7934448\/revisions"}],"predecessor-version":[{"id":8172176,"href":"https:\/\/www.wildix.com\/fr\/wp-json\/wp\/v2\/case-studies\/7934448\/revisions\/8172176"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.wildix.com\/fr\/wp-json\/wp\/v2\/media\/7906060"}],"wp:attachment":[{"href":"https:\/\/www.wildix.com\/fr\/wp-json\/wp\/v2\/media?parent=7934448"}],"wp:term":[{"taxonomy":"case_study_industry","embeddable":true,"href":"https:\/\/www.wildix.com\/fr\/wp-json\/wp\/v2\/case_study_industry?post=7934448"},{"taxonomy":"case_study_region","embeddable":true,"href":"https:\/\/www.wildix.com\/fr\/wp-json\/wp\/v2\/case_study_region?post=7934448"},{"taxonomy":"case_study_size","embeddable":true,"href":"https:\/\/www.wildix.com\/fr\/wp-json\/wp\/v2\/case_study_size?post=7934448"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}