{"id":8062744,"date":"2023-12-13T01:00:18","date_gmt":"2023-12-13T00:00:18","guid":{"rendered":"https:\/\/www.wildix.com\/wildix-2023-gartner-magic-quadrant-ucaas-recognition\/"},"modified":"2024-04-15T18:14:11","modified_gmt":"2024-04-15T16:14:11","slug":"wildix-2023-gartner-magic-quadrant-ucaas-reconocimiento","status":"publish","type":"post","link":"https:\/\/www.wildix.com\/es\/wildix-2023-gartner-magic-quadrant-ucaas-reconocimiento\/","title":{"rendered":"Wildix se posiciona como niche player en el Gartner\u00ae Magic Quadrant\u2122 de 2023 para Comunicaciones unificadas as a service"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"8062744\" class=\"elementor elementor-8062744 elementor-8062686\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f1c6a23 e-con-full e-flex e-con e-child\" data-id=\"f1c6a23\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-58bc8f1 elementor-widget elementor-widget-text-editor\" data-id=\"58bc8f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<span style=\"background-color: #003366; color: #ffffff; padding: 10px 10px 10px 10px; border-radius: 3px;\">Nota de Prensa<\/span>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a1ab0c1 e-con-full e-flex e-con e-child\" data-id=\"a1ab0c1\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t<div class=\"elementor-element elementor-element-5b5ac34 e-con-full e-flex e-con e-child\" data-id=\"5b5ac34\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f4536ce elementor-widget elementor-widget-text-editor\" data-id=\"f4536ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tTallinn, Estonia \u2013 Mi\u00e9rcoles, 13 de diciembre, 2023 \u2013 Wildix, el proveedor en crecimiento de soluciones de Comunicaciones Unificadas \u201cAs a Service\u201d, ha anunciado hoy que ha sido posicionado por Gartner\u00ae como Niche Player en el Gartner\u00ae Magic Quadrant\u2122 de 2023. Creemos que esta diferencia destaca el compromiso de Wildix de proporcionar soluciones de Comunicaciones Unificadas as a Service (UCaaS) innovadoras y efectivas, adaptadas espec\u00edficamente a las necesidades empresariales.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f29a9fc e-con-full e-flex e-con e-child\" data-id=\"f29a9fc\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e8b7d9d elementor-widget elementor-widget-image\" data-id=\"e8b7d9d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1200\" height=\"630\" src=\"https:\/\/www.wildix.com\/wp-content\/uploads\/2023\/12\/magic-quadrant.webp\" class=\"attachment-full size-full wp-image-8062683\" alt=\"Wildix recognised as a niche player in the 2023 Gartner\u00ae Magic Quadrant\u2122 for unified communications as a service\" srcset=\"https:\/\/www.wildix.com\/wp-content\/uploads\/2023\/12\/magic-quadrant.webp 1200w, https:\/\/www.wildix.com\/wp-content\/uploads\/2023\/12\/magic-quadrant-300x158.webp 300w, https:\/\/www.wildix.com\/wp-content\/uploads\/2023\/12\/magic-quadrant-1024x538.webp 1024w, https:\/\/www.wildix.com\/wp-content\/uploads\/2023\/12\/magic-quadrant-768x403.webp 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4d78aea testimonials-block elementor-widget elementor-widget-testimonial\" data-id=\"4d78aea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"testimonial.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial-wrapper\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial-content\">Nos emociona ser reconocidos en el Gartner\u00ae Magic Quadrant\u2122. Para nosotros, este reconocimiento no solo representa el dedicado empe\u00f1o de nuestro equipo en proporcionar soluciones UCaaS de calidad, sino que tambi\u00e9n nos impulsa a continuar perfeccionando nuestros servicios. Nuestra dedicaci\u00f3n a la evoluci\u00f3n de nuestras ofertas y a la expansi\u00f3n de la presencia en el mercado persiste, con el objetivo de satisfacer las cambiantes necesidades y demandas de las organizaciones a nivel mundial, y manteniendo un enfoque inalterable en el canal al 100%.<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-testimonial-meta elementor-has-image elementor-testimonial-image-position-aside\">\n\t\t\t\t<div class=\"elementor-testimonial-meta-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.wildix.com\/wp-content\/uploads\/2022\/12\/steve-osler_400x400-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-image-7994715\" alt=\"Steve Osler\" srcset=\"https:\/\/www.wildix.com\/wp-content\/uploads\/2022\/12\/steve-osler_400x400-150x150.jpg 150w, https:\/\/www.wildix.com\/wp-content\/uploads\/2022\/12\/steve-osler_400x400-300x300.jpg 300w, https:\/\/www.wildix.com\/wp-content\/uploads\/2022\/12\/steve-osler_400x400.jpg 400w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-details\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-name\">Steve Osler<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-job\">Fundador y CEO de Wildix<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-43435dc elementor-widget elementor-widget-text-editor\" data-id=\"43435dc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tLas soluciones de Wildix han sido dise\u00f1adas para permitir una comunicaci\u00f3n y colaboraci\u00f3n fluidas. Las m\u00e1s recientes mejoras de la empresa, como servicio de reserva de reuniones disponible para invitados, chat integrado en la reuni\u00f3n, el an\u00e1lisis de sentimientos para los participantes de la reuni\u00f3n, la subtitulaci\u00f3n autom\u00e1tica y las actualizaciones de presencia m\u00f3vil, demuestran la dedicaci\u00f3n de Wildix a la mejora continua y la innovaci\u00f3n centrada en el usuario.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-da0459a testimonials-block elementor-widget elementor-widget-testimonial\" data-id=\"da0459a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"testimonial.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial-wrapper\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial-content\">El reconocimiento no solo confirma la calidad de nuestros productos, sino que tambi\u00e9n habla de nuestros logros pasados y de nuestra visi\u00f3n futura. Estamos en el camino de fortalecer nuestra presencia en el mercado,  gracias al desarrollo estrat\u00e9gico y a nuestra ambici\u00f3n de ser la elecci\u00f3n preferida para los Proveedores de Servicios Gestionados (MSP) y sus clientes. Con este reconocimiento, nos preparamos para el pr\u00f3ximo <a href=\"https:\/\/www.uc-summit.com\/\" target=\"_blank\" rel=\"noopener\">UC&amp;C Summit virtual de 2024<\/a>, donde destacaremos nuestras iniciativas m\u00e1s recientes y compartiremos valiosas perspectivas de mercado.<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-testimonial-meta elementor-has-image elementor-testimonial-image-position-aside\">\n\t\t\t\t<div class=\"elementor-testimonial-meta-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.wildix.com\/wp-content\/uploads\/2021\/03\/emiliano-tomasoni-smo-at-wildix-150x150.jpeg\" class=\"attachment-thumbnail size-thumbnail wp-image-7869499\" alt=\"Emiliano Tomasoni\" srcset=\"https:\/\/www.wildix.com\/wp-content\/uploads\/2021\/03\/emiliano-tomasoni-smo-at-wildix-150x150.jpeg 150w, https:\/\/www.wildix.com\/wp-content\/uploads\/2021\/03\/emiliano-tomasoni-smo-at-wildix-300x300.jpeg 300w, https:\/\/www.wildix.com\/wp-content\/uploads\/2021\/03\/emiliano-tomasoni-smo-at-wildix.jpeg 428w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-details\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-name\">Emiliano Tomasoni<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-job\">CMO de Wildix<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ac20cdb e-con-full e-flex e-con e-child\" data-id=\"ac20cdb\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0398dc8 elementor-widget elementor-widget-text-editor\" data-id=\"0398dc8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tGartner\u00ae, Magic Quadrant\u2122 for Unified Communications as a Service, 28 de Noviembre 2023. GARTNER\u00ae es una marca comercial registrada y marca de servicio de Gartner\u00ae, Inc. y\/o sus afiliados en los Estados Unidos e internacionalmente, y MAGIC QUADRANT\u2122 es una marca comercial registrada de Gartner\u00ae, Inc. y\/o sus afiliados, y se utilizan aqu\u00ed con permiso. Todos los derechos reservados.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0525e15 elementor-widget elementor-widget-text-editor\" data-id=\"0525e15\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tGartner\u00ae no respalda a ning\u00fan proveedor, producto o servicio que aparezca en sus publicaciones de investigaci\u00f3n, y no aconseja a los usuarios de tecnolog\u00eda que elijan exclusivamente a aquellos proveedores con las calificaciones m\u00e1s altas u otras designaciones. Las publicaciones de investigaci\u00f3n de Gartner\u00ae representan las opiniones de la organizaci\u00f3n de investigaci\u00f3n de Gartner\u00ae y no deben ser interpretadas como afirmaciones de hechos. Gartner\u00ae no ofrece ninguna garant\u00eda, ya sea expresa o impl\u00edcita, en relaci\u00f3n con esta investigaci\u00f3n, incluyendo cualquier garant\u00eda de comercialidad o idoneidad para un prop\u00f3sito espec\u00edfico.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Nota de PrensaTallinn, Estonia \u2013 Mi\u00e9rcoles, 13 de diciembre, 2023 \u2013 Wildix, el proveedor en crecimiento de soluciones de Comunicaciones Unificadas \u201cAs a Service\u201d, ha anunciado hoy que ha sido posicionado por Gartner\u00ae como Niche Player en el Gartner\u00ae Magic Quadrant\u2122 de 2023. Creemos que esta diferencia destaca el compromiso de Wildix de proporcionar soluciones [&hellip;]<\/p>\n","protected":false},"author":51,"featured_media":8062683,"parent":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_jet_sm_ready_style":"","_jet_sm_style":"","_jet_sm_controls_values":"","_jet_sm_fonts_collection":"","_jet_sm_fonts_links":"","footnotes":""},"categories":[865],"tags":[],"class_list":["post-8062744","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news-spa"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Wildix se posiciona como Niche Player en el Gartner Magic Quadrant de 2023 para Comunicaciones Unificadas As a Service | Wildix<\/title>\n<meta name=\"description\" content=\"Wildix, un proveedor innovador de Comunicaciones Unificadas As a Service, ha sido reconocido como Niche Player en el Gartner Magic Quadrant para Comunicaciones Unificadas As a Service (UCaaS). Descubre c\u00f3mo las soluciones innovadoras de Wildix y su compromiso con la excelencia est\u00e1n transformando las comunicaciones y la colaboraci\u00f3n empresarial.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wildix se posiciona como Niche Player en el Gartner Magic Quadrant de 2023 para Comunicaciones Unificadas As a Service | Wildix\" \/>\n<meta property=\"og:description\" content=\"Wildix, un proveedor innovador de Comunicaciones Unificadas As a Service, ha sido reconocido como Niche Player en el Gartner Magic Quadrant para Comunicaciones Unificadas As a Service (UCaaS). Descubre c\u00f3mo las soluciones innovadoras de Wildix y su compromiso con la excelencia est\u00e1n transformando las comunicaciones y la colaboraci\u00f3n empresarial.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.wildix.com\/es\/wildix-2023-gartner-magic-quadrant-ucaas-reconocimiento\/\" \/>\n<meta property=\"og:site_name\" content=\"Wildix\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/groups\/wildixtechwizards\/?mibextid=6NoCDW\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-13T00:00:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-15T16:14:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.wildix.com\/wp-content\/uploads\/2023\/12\/magic-quadrant.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Oksana Troshyna\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@wildix_\" \/>\n<meta name=\"twitter:site\" content=\"@wildix_\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Oksana Troshyna\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wildix se posiciona como Niche Player en el Gartner Magic Quadrant de 2023 para Comunicaciones Unificadas As a Service | Wildix","description":"Wildix, un proveedor innovador de Comunicaciones Unificadas As a Service, ha sido reconocido como Niche Player en el Gartner Magic Quadrant para Comunicaciones Unificadas As a Service (UCaaS). Descubre c\u00f3mo las soluciones innovadoras de Wildix y su compromiso con la excelencia est\u00e1n transformando las comunicaciones y la colaboraci\u00f3n empresarial.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"es_ES","og_type":"article","og_title":"Wildix se posiciona como Niche Player en el Gartner Magic Quadrant de 2023 para Comunicaciones Unificadas As a Service | Wildix","og_description":"Wildix, un proveedor innovador de Comunicaciones Unificadas As a Service, ha sido reconocido como Niche Player en el Gartner Magic Quadrant para Comunicaciones Unificadas As a Service (UCaaS). Descubre c\u00f3mo las soluciones innovadoras de Wildix y su compromiso con la excelencia est\u00e1n transformando las comunicaciones y la colaboraci\u00f3n empresarial.","og_url":"https:\/\/www.wildix.com\/es\/wildix-2023-gartner-magic-quadrant-ucaas-reconocimiento\/","og_site_name":"Wildix","article_publisher":"https:\/\/www.facebook.com\/groups\/wildixtechwizards\/?mibextid=6NoCDW","article_published_time":"2023-12-13T00:00:18+00:00","article_modified_time":"2024-04-15T16:14:11+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.wildix.com\/wp-content\/uploads\/2023\/12\/magic-quadrant.webp","type":"image\/webp"}],"author":"Oksana Troshyna","twitter_card":"summary_large_image","twitter_creator":"@wildix_","twitter_site":"@wildix_","twitter_misc":{"Escrito por":"Oksana Troshyna","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.wildix.com\/es\/wildix-2023-gartner-magic-quadrant-ucaas-reconocimiento\/#article","isPartOf":{"@id":"https:\/\/www.wildix.com\/es\/wildix-2023-gartner-magic-quadrant-ucaas-reconocimiento\/"},"author":{"name":"Oksana Troshyna","@id":"https:\/\/www.wildix.com\/es\/#\/schema\/person\/6c8661146e4fc1b692f037dcbe713c41"},"headline":"Wildix se posiciona como niche player en el Gartner\u00ae Magic Quadrant\u2122 de 2023 para Comunicaciones unificadas as a service","datePublished":"2023-12-13T00:00:18+00:00","dateModified":"2024-04-15T16:14:11+00:00","mainEntityOfPage":{"@id":"https:\/\/www.wildix.com\/es\/wildix-2023-gartner-magic-quadrant-ucaas-reconocimiento\/"},"wordCount":518,"publisher":{"@id":"https:\/\/www.wildix.com\/es\/#organization"},"image":{"@id":"https:\/\/www.wildix.com\/es\/wildix-2023-gartner-magic-quadrant-ucaas-reconocimiento\/#primaryimage"},"thumbnailUrl":"https:\/\/www.wildix.com\/wp-content\/uploads\/2023\/12\/magic-quadrant.webp","articleSection":["News SPA"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.wildix.com\/es\/wildix-2023-gartner-magic-quadrant-ucaas-reconocimiento\/","url":"https:\/\/www.wildix.com\/es\/wildix-2023-gartner-magic-quadrant-ucaas-reconocimiento\/","name":"Wildix se posiciona como Niche Player en el Gartner Magic Quadrant de 2023 para Comunicaciones Unificadas As a Service | Wildix","isPartOf":{"@id":"https:\/\/www.wildix.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.wildix.com\/es\/wildix-2023-gartner-magic-quadrant-ucaas-reconocimiento\/#primaryimage"},"image":{"@id":"https:\/\/www.wildix.com\/es\/wildix-2023-gartner-magic-quadrant-ucaas-reconocimiento\/#primaryimage"},"thumbnailUrl":"https:\/\/www.wildix.com\/wp-content\/uploads\/2023\/12\/magic-quadrant.webp","datePublished":"2023-12-13T00:00:18+00:00","dateModified":"2024-04-15T16:14:11+00:00","description":"Wildix, un proveedor innovador de Comunicaciones Unificadas As a Service, ha sido reconocido como Niche Player en el Gartner Magic Quadrant para Comunicaciones Unificadas As a Service (UCaaS). Descubre c\u00f3mo las soluciones innovadoras de Wildix y su compromiso con la excelencia est\u00e1n transformando las comunicaciones y la colaboraci\u00f3n empresarial.","breadcrumb":{"@id":"https:\/\/www.wildix.com\/es\/wildix-2023-gartner-magic-quadrant-ucaas-reconocimiento\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.wildix.com\/es\/wildix-2023-gartner-magic-quadrant-ucaas-reconocimiento\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.wildix.com\/es\/wildix-2023-gartner-magic-quadrant-ucaas-reconocimiento\/#primaryimage","url":"https:\/\/www.wildix.com\/wp-content\/uploads\/2023\/12\/magic-quadrant.webp","contentUrl":"https:\/\/www.wildix.com\/wp-content\/uploads\/2023\/12\/magic-quadrant.webp","width":1200,"height":630,"caption":"Wildix recognised as a niche player in the 2023 Gartner\u00ae Magic Quadrant\u2122 for unified communications as a service"},{"@type":"BreadcrumbList","@id":"https:\/\/www.wildix.com\/es\/wildix-2023-gartner-magic-quadrant-ucaas-reconocimiento\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.wildix.com\/es\/"},{"@type":"ListItem","position":2,"name":"Wildix se posiciona como niche player en el Gartner\u00ae Magic Quadrant\u2122 de 2023 para Comunicaciones unificadas as a service"}]},{"@type":"WebSite","@id":"https:\/\/www.wildix.com\/es\/#website","url":"https:\/\/www.wildix.com\/es\/","name":"Wildix","description":"","publisher":{"@id":"https:\/\/www.wildix.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.wildix.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.wildix.com\/es\/#organization","name":"Wildix","url":"https:\/\/www.wildix.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.wildix.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.wildix.com\/wp-content\/uploads\/2021\/09\/logo-1.svg","contentUrl":"https:\/\/www.wildix.com\/wp-content\/uploads\/2021\/09\/logo-1.svg","caption":"Wildix"},"image":{"@id":"https:\/\/www.wildix.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/groups\/wildixtechwizards\/?mibextid=6NoCDW","https:\/\/x.com\/wildix_"]},{"@type":"Person","@id":"https:\/\/www.wildix.com\/es\/#\/schema\/person\/6c8661146e4fc1b692f037dcbe713c41","name":"Oksana Troshyna","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/9576dcb9c3d786b0c81f0e89e9d2f0866d5348775664c07b0ee35e68afa7475a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9576dcb9c3d786b0c81f0e89e9d2f0866d5348775664c07b0ee35e68afa7475a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9576dcb9c3d786b0c81f0e89e9d2f0866d5348775664c07b0ee35e68afa7475a?s=96&d=mm&r=g","caption":"Oksana Troshyna"}}]}},"clean_content":"Nota de Prensa Tallinn, Estonia \u2013 Mi\u00e9rcoles, 13 de diciembre, 2023 \u2013 Wildix, el proveedor en crecimiento de soluciones de Comunicaciones Unificadas \u201cAs a Service\u201d, ha anunciado hoy que ha sido posicionado por Gartner\u00ae como Niche Player en el Gartner\u00ae Magic Quadrant\u2122 de 2023. Creemos que esta diferencia destaca el compromiso de Wildix de proporcionar soluciones de Comunicaciones Unificadas as a Service (UCaaS) innovadoras y efectivas, adaptadas espec\u00edficamente a las necesidades empresariales. Nos emociona ser reconocidos en el Gartner\u00ae Magic Quadrant\u2122. Para nosotros, este reconocimiento no solo representa el dedicado empe\u00f1o de nuestro equipo en proporcionar soluciones UCaaS de calidad, sino que tambi\u00e9n nos impulsa a continuar perfeccionando nuestros servicios. Nuestra dedicaci\u00f3n a la evoluci\u00f3n de nuestras ofertas y a la expansi\u00f3n de la presencia en el mercado persiste, con el objetivo de satisfacer las cambiantes necesidades y demandas de las organizaciones a nivel mundial, y manteniendo un enfoque inalterable en el canal al 100%. Steve Osler Fundador y CEO de Wildix Las soluciones de Wildix han sido dise\u00f1adas para permitir una comunicaci\u00f3n y colaboraci\u00f3n fluidas. Las m\u00e1s recientes mejoras de la empresa, como servicio de reserva de reuniones disponible para invitados, chat integrado en la reuni\u00f3n, el an\u00e1lisis de sentimientos para los participantes de la reuni\u00f3n, la subtitulaci\u00f3n autom\u00e1tica y las actualizaciones de presencia m\u00f3vil, demuestran la dedicaci\u00f3n de Wildix a la mejora continua y la innovaci\u00f3n centrada en el usuario. El reconocimiento no solo confirma la calidad de nuestros productos, sino que tambi\u00e9n habla de nuestros logros pasados y de nuestra visi\u00f3n futura. Estamos en el camino de fortalecer nuestra presencia en el mercado, gracias al desarrollo estrat\u00e9gico y a nuestra ambici\u00f3n de ser la elecci\u00f3n preferida para los Proveedores de Servicios Gestionados (MSP) y sus clientes. Con este reconocimiento, nos preparamos para el pr\u00f3ximo UC&C Summit virtual de 2024, donde destacaremos nuestras iniciativas m\u00e1s recientes y compartiremos valiosas perspectivas de mercado. Emiliano Tomasoni CMO de Wildix Gartner\u00ae, Magic Quadrant\u2122 for Unified Communications as a Service, 28 de Noviembre 2023. GARTNER\u00ae es una marca comercial registrada y marca de servicio de Gartner\u00ae, Inc. y\/o sus afiliados en los Estados Unidos e internacionalmente, y MAGIC QUADRANT\u2122 es una marca comercial registrada de Gartner\u00ae, Inc. y\/o sus afiliados, y se utilizan aqu\u00ed con permiso. Todos los derechos reservados. Gartner\u00ae no respalda a ning\u00fan proveedor, producto o servicio que aparezca en sus publicaciones de investigaci\u00f3n, y no aconseja a los usuarios de tecnolog\u00eda que elijan exclusivamente a aquellos proveedores con las calificaciones m\u00e1s altas u otras designaciones. Las publicaciones de investigaci\u00f3n de Gartner\u00ae representan las opiniones de la organizaci\u00f3n de investigaci\u00f3n de Gartner\u00ae y no deben ser interpretadas como afirmaciones de hechos. Gartner\u00ae no ofrece ninguna garant\u00eda, ya sea expresa o impl\u00edcita, en relaci\u00f3n con esta investigaci\u00f3n, incluyendo cualquier garant\u00eda de comercialidad o idoneidad para un prop\u00f3sito espec\u00edfico.","clean_excerpt":"Nota de PrensaTallinn, Estonia \u2013 Mi\u00e9rcoles, 13 de diciembre, 2023 \u2013 Wildix, el proveedor en crecimiento de soluciones de Comunicaciones Unificadas \u201cAs a Service\u201d, ha anunciado hoy que ha sido posicionado por Gartner\u00ae como Niche Player en el Gartner\u00ae Magic Quadrant\u2122 de 2023. Creemos que esta diferencia destaca el compromiso de Wildix de proporcionar soluciones...","_links":{"self":[{"href":"https:\/\/www.wildix.com\/es\/wp-json\/wp\/v2\/posts\/8062744","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.wildix.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.wildix.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.wildix.com\/es\/wp-json\/wp\/v2\/users\/51"}],"replies":[{"embeddable":true,"href":"https:\/\/www.wildix.com\/es\/wp-json\/wp\/v2\/comments?post=8062744"}],"version-history":[{"count":5,"href":"https:\/\/www.wildix.com\/es\/wp-json\/wp\/v2\/posts\/8062744\/revisions"}],"predecessor-version":[{"id":8074275,"href":"https:\/\/www.wildix.com\/es\/wp-json\/wp\/v2\/posts\/8062744\/revisions\/8074275"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.wildix.com\/es\/wp-json\/wp\/v2\/media\/8062683"}],"wp:attachment":[{"href":"https:\/\/www.wildix.com\/es\/wp-json\/wp\/v2\/media?parent=8062744"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.wildix.com\/es\/wp-json\/wp\/v2\/categories?post=8062744"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.wildix.com\/es\/wp-json\/wp\/v2\/tags?post=8062744"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}