{"id":8085763,"date":"2024-04-30T16:02:58","date_gmt":"2024-04-30T14:02:58","guid":{"rendered":"https:\/\/www.wildix.com\/?post_type=email-news&#038;p=8085763"},"modified":"2024-04-30T16:03:00","modified_gmt":"2024-04-30T14:03:00","slug":"apr-12-2024-neuigkeiten-vom-qph-q2-2024","status":"publish","type":"email-news","link":"https:\/\/www.wildix.com\/es\/email-news\/apr-12-2024-neuigkeiten-vom-qph-q2-2024\/","title":{"rendered":"Apr 12, 2024 \u2013 Neuigkeiten vom QPH Q2\/2024"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Das zweite Quartal ist bereits rasant angelaufen und als Follow Up zu unserem zweiten Quarterly Partner Huddle Meeting in diesem Jahr m\u00f6chten wir Ihnen die wichtigsten Infos noch einmal zusammenfassen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Wildix gewinnt Gold<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bei den Telecom 2024 Merit Awards erhielt Wildix&nbsp;<a target=\"_blank\" href=\"https:\/\/www.wildix.com\/wildix-wins-gold-2024-merit-awards\/\" rel=\"noreferrer noopener\">Gold<\/a>&nbsp;f\u00fcr die f\u00fchrende Rolle im Bereich WebRTC, was unsere besondere Leistung in diesem Bereich unterstreicht, bereits im Jahr 2013 als erstes Unternehmen WebRTC in UC&amp;C integriert zu haben. Zudem erhielten wir Bronze im Bereich &#8220;Business Services&#8221;. Diese Auszeichnungen spiegeln unsere unerm\u00fcdliches Engagement f\u00fcr die Weiterentwicklung unserer UC&amp;C-L\u00f6sungen wider.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Community und Rewards<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durch den \u00dcbergang auf die Salesforce Partner Community&nbsp;haben wir schon in den ersten 3 Monaten einen exponentiellen Anstieg der Opportunities von Monat zu Monat verzeichnet: 330 im Januar, 611 im Februar, 842 im M\u00e4rz. 85 % des globalen MRR im M\u00e4rz haben somit die SFPC durchlaufen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Partner Community bietet jetzt neue Ressourcen und Tools. Unter anderem geh\u00f6ren dazu&nbsp;exklusive Tutorials und die M\u00f6glichkeit, Veesion-Lizenzen direkt zu verkaufen. Unsere verbesserten Bestell- und Bereitstellungsprozesse wurden weiterentwickelt, um Ihr Wachstum zu f\u00f6rdern und die Nutzung von Wildix-L\u00f6sungen zu optimieren.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Einf\u00fchrung des&nbsp;Pipeline Bonus<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In diesem Quartal haben wir einen Pipeline Bonus f\u00fcr Vertriebsmitarbeiter eingef\u00fchrt, die nach einer Demo Feedback geben, sofern der Account Manager dies genehmigt. Zudem werden die&nbsp;PBX\/Systeme&nbsp;in die Partner Community integriert.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Innovationen und Produkthighlights<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In Q1 haben wir einen Ausblick auf kommende Funktionen und L\u00f6sungen gegeben. Nun wurden diese erfolgreich implementiert:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Die neueste Telefon-Serie:<\/strong>\u00a0Wir haben WelcomeConsole 5, Start 5, WorkForce 5 und das neue ForcePro 5 vorgestellt, die alle \u00fcber HWaaS verf\u00fcgbar sind. Diese Telefone wurden entwickelt, um unterschiedliche Gesch\u00e4ftsanforderungen zu erf\u00fcllen.<\/li>\n\n\n\n<li><strong>DECT ATEX Telefon:\u00a0<\/strong>Dieses Telefon, das die Wildix W-AIR-Familie erweitert, wurde f\u00fcr explosionsgef\u00e4hrdete Umgebungen entwickelt, um Sicherheit und Kommunikation ohne Kompromisse zu gew\u00e4hrleisten. Die Markteinf\u00fchrung ist f\u00fcr das dritte Quartal 2024 geplant.\u00a0<\/li>\n\n\n\n<li><strong>x-bees:\u00a0<\/strong>Unsere Plattform bietet jetzt Echtzeit-Transkription, KI-Chat-Unterst\u00fctzung und bald auch Stimmungsanalyse sowie die neue Funktion &#8220;Insights&#8221;, die einen ganzheitlichen Ansatz zur Analyse von Kundeninteraktionen bietet.<\/li>\n\n\n\n<li><strong>CLASSOUND:<\/strong>\u00a0J\u00fcngste Updates haben die Online-DID-Bereitstellung und eine spezielle CTA f\u00fcr Premium-Nummern eingef\u00fchrt. In K\u00fcrze werden wir\u00a0permanenten virtuellen DIDs und einer verbesserten WhatsApp Business-Integration \u00fcber x-bees hinzuf\u00fcgen.<\/li>\n\n\n\n<li><strong>Produktinnovationen und Updates:<\/strong>\u00a0Unsere Collaboration-Plattform unterst\u00fctzt nun auch die arabische\u00a0Sprache, wodurch wir unsere globale Reichweite erh\u00f6hen. Dar\u00fcber hinaus erm\u00f6glicht unsere Integration mit Bigin by Zoho jetzt Click-to-Call-Funktionen und sofortige Anrufbenachrichtigungen aus Kundendatens\u00e4tzen, was die Kommunikation vereinfacht und die Effizienz steigert.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>x-hoppers im Rampenlicht<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wir begr\u00fc\u00dfen Ian Rowan als Global Sales Manager f\u00fcr x-hoppers, der mit seiner Expertise wesentlich zu unserer globalen Expansion beitragen wird. Wir freuen uns auch \u00fcber die j\u00fcngsten Auszeichnungen von x-hoppers bei den Telecom 2024 Merit Awards, darunter Gold f\u00fcr &#8220;AI Services&#8221; und Silber f\u00fcr &#8220;Connecting the Unconnected&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Neue Funktionen f\u00fcr x-hoppers in diesem Quartal sind beispielsweise&nbsp;die&nbsp;Anzeige des Batteriestands der Headsets und die Sprachauthentifizierung f\u00fcr Mitarbeiter in Gesch\u00e4ften. x-hoppers hat au\u00dferdem vor kurzem die FTR (Foundational Technical Review) von AWS bestanden, die best\u00e4tigt, dass das Produkt alle Anforderungen von AWS erf\u00fcllt. Weitere kommende Updates f\u00fcr mehr Effizienz: die M\u00f6glichkeit, Nachrichten zu senden, ein Wallboard zur \u00dcberwachung des Headset-Akkustands und detaillierte Informationen dar\u00fcber, wer eine Anfrage von einem Help Point bearbeitet hat, einschlie\u00dflich Wartezeiten und anderer relevanter Daten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Strategische Preisanpassung f\u00fcr mehr Wachstum<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Im ersten Quartal hat Wildix mit dem Upgrade auf WMS 6.05 erweiterte Preispakete f\u00fcr Speicher eingef\u00fchrt, die erhebliche Kostensenkungen erm\u00f6glichen&nbsp;\u2013&nbsp;im gr\u00f6\u00dften Paket (CDS-5000) bis zu 94%. Zudem bieten sie l\u00e4ngere Datenspeicherzeiten f\u00fcr Cloud-Analysen, wodurch der Mehrwert und die Effizienz optimiert werden.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/go.pardot.com\/l\/920113\/2024-04-04\/2h26d2\/920113\/17122384954KJ00dAu\/Bildschirmfoto_2024_04_04_um_15.47.45.png\" alt=\"\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Bestellprozess f\u00fcr neue Telefone<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In K\u00fcrze k\u00f6nnen Partner unsere neue Telefonserie \u00fcber ein Deposit-basiertes System bestellen. Diese&nbsp;m\u00fcssen innerhalb von 6 Monaten in HWaaS umgewandelt werden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Kaution Pauschalgeb\u00fchren:<\/em><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Start 5: 70 Euro<\/li>\n\n\n\n<li>Workforce 5: 80 Euro<\/li>\n\n\n\n<li>ForcePro 5: 100 Euro<\/li>\n\n\n\n<li>WelcomeConsole 5: 100 Euro<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Reduktion der Pauschalgeb\u00fchr basierend auf der Menge:<\/em><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>0-9 Einheiten: 0% Rabatt<\/li>\n\n\n\n<li>10-49 Einheiten: 5% Rabatt<\/li>\n\n\n\n<li>50-99 Einheiten: 20% Rabatt<\/li>\n\n\n\n<li>100+ Einheiten: 50% Rabatt<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Marketing und Vertrieb<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Unsere Expansion in den Nahen Osten und der Erfolg unserer Partner bei der Generierung von Endkundenkontakten markieren eine neue Wachstumsphase, die im zweiten Quartal 2024 Fahrt aufnimmt. Dar\u00fcber hinaus haben wir unsere E-Learning-Plattform f\u00fcr G\u00e4ste verf\u00fcgbar gemacht, um sie auch f\u00fcr&nbsp;Ihre&nbsp;Endbenutzer zug\u00e4nglich zu machen. Wenn Sie noch nicht Teil der Wildix Partner Community&nbsp;sind, k\u00f6nnen Sie sich hier f\u00fcr die E-Learning-Plattform registrieren:&nbsp;<a target=\"_blank\" href=\"https:\/\/www.wildix.com\/join-e-learning\" rel=\"noreferrer noopener\">www.wildix.com\/join-e-learning<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Vertriebsunterst\u00fctzung<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Allen Partnern, die ihre HWaaS-MRR-Ziele f\u00fcr 2023 nicht erreicht haben, bieten wir eine Gelegenheit, unsere neuen Telefone ohne Vorabkosten zu testen. Nat\u00fcrlich gilt das auch f\u00fcr Partner, die in 2023 100 Euro in HWaaS mehr als in 2022 umgesetzt haben.&nbsp;Voraussetzung f\u00fcr die Teilnahme ist die Verpflichtung, den HWaaS-basierten MRR im ersten Halbjahr 2024 \u00fcber die Zahlen vom Dezember 2023 hinaus zu steigern.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Wir feiern den Erfolg unserer Partner<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u200b\u200b\u200b\u200b\u200bGlobal gesehen hat die ITAS es auch in diesem Quartal aufs Treppchen geschafft (Platz 2), doch wie sieht es in Deutschland und \u00d6sterreich aus?&nbsp;Wir bedanken uns f\u00fcr Ihren Einsatz und gratulieren herzlich unseren Top 3:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Deutschland<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>ITAS<\/li>\n\n\n\n<li>COMJECT<\/li>\n\n\n\n<li>GfK System<\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">\u00d6sterreich<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>TOOL IT<\/li>\n\n\n\n<li>Capro<\/li>\n\n\n\n<li>Computer Sanz<\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">Schweiz<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>NETKUM<\/li>\n\n\n\n<li>PrimeNet<\/li>\n\n\n\n<li>TeleConnex<\/li>\n\n\n\n<li>Speri &amp; B\u00fctler<\/li>\n\n\n\n<li>N\u00fcnlist<\/li>\n<\/ol>\n","protected":false},"excerpt":{"rendered":"<p>Das zweite Quartal ist bereits rasant angelaufen und als Follow Up zu unserem zweiten Quarterly Partner Huddle Meeting in diesem Jahr m\u00f6chten wir Ihnen die wichtigsten Infos noch einmal zusammenfassen. Wildix gewinnt Gold Bei den Telecom 2024 Merit Awards erhielt Wildix&nbsp;Gold&nbsp;f\u00fcr die f\u00fchrende Rolle im Bereich WebRTC, was unsere besondere Leistung in diesem Bereich unterstreicht, [&hellip;]<\/p>\n","protected":false},"author":26,"featured_media":0,"parent":0,"template":"","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_jet_sm_ready_style":"","_jet_sm_style":"","_jet_sm_controls_values":"","_jet_sm_fonts_collection":"","_jet_sm_fonts_links":""},"class_list":["post-8085763","email-news","type-email-news","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Apr 12, 2024 \u2013 Neuigkeiten vom QPH Q2\/2024 | Wildix<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Apr 12, 2024 \u2013 Neuigkeiten vom QPH Q2\/2024 | Wildix\" \/>\n<meta property=\"og:description\" content=\"Das zweite Quartal ist bereits rasant angelaufen und als Follow Up zu unserem zweiten Quarterly Partner Huddle Meeting in diesem Jahr m\u00f6chten wir Ihnen die wichtigsten Infos noch einmal zusammenfassen. Wildix gewinnt Gold Bei den Telecom 2024 Merit Awards erhielt Wildix&nbsp;Gold&nbsp;f\u00fcr die f\u00fchrende Rolle im Bereich WebRTC, was unsere besondere Leistung in diesem Bereich unterstreicht, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.wildix.com\/es\/email-news\/apr-12-2024-neuigkeiten-vom-qph-q2-2024\/\" \/>\n<meta property=\"og:site_name\" content=\"Wildix\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/groups\/wildixtechwizards\/?mibextid=6NoCDW\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-30T14:03:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/go.pardot.com\/l\/920113\/2024-04-04\/2h26d2\/920113\/17122384954KJ00dAu\/Bildschirmfoto_2024_04_04_um_15.47.45.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@wildix_\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Apr 12, 2024 \u2013 Neuigkeiten vom QPH Q2\/2024 | Wildix","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Apr 12, 2024 \u2013 Neuigkeiten vom QPH Q2\/2024 | Wildix","og_description":"Das zweite Quartal ist bereits rasant angelaufen und als Follow Up zu unserem zweiten Quarterly Partner Huddle Meeting in diesem Jahr m\u00f6chten wir Ihnen die wichtigsten Infos noch einmal zusammenfassen. Wildix gewinnt Gold Bei den Telecom 2024 Merit Awards erhielt Wildix&nbsp;Gold&nbsp;f\u00fcr die f\u00fchrende Rolle im Bereich WebRTC, was unsere besondere Leistung in diesem Bereich unterstreicht, [&hellip;]","og_url":"https:\/\/www.wildix.com\/es\/email-news\/apr-12-2024-neuigkeiten-vom-qph-q2-2024\/","og_site_name":"Wildix","article_publisher":"https:\/\/www.facebook.com\/groups\/wildixtechwizards\/?mibextid=6NoCDW","article_modified_time":"2024-04-30T14:03:00+00:00","og_image":[{"url":"https:\/\/go.pardot.com\/l\/920113\/2024-04-04\/2h26d2\/920113\/17122384954KJ00dAu\/Bildschirmfoto_2024_04_04_um_15.47.45.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@wildix_","twitter_misc":{"Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.wildix.com\/es\/email-news\/apr-12-2024-neuigkeiten-vom-qph-q2-2024\/","url":"https:\/\/www.wildix.com\/es\/email-news\/apr-12-2024-neuigkeiten-vom-qph-q2-2024\/","name":"Apr 12, 2024 \u2013 Neuigkeiten vom QPH Q2\/2024 | Wildix","isPartOf":{"@id":"https:\/\/www.wildix.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.wildix.com\/es\/email-news\/apr-12-2024-neuigkeiten-vom-qph-q2-2024\/#primaryimage"},"image":{"@id":"https:\/\/www.wildix.com\/es\/email-news\/apr-12-2024-neuigkeiten-vom-qph-q2-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/go.pardot.com\/l\/920113\/2024-04-04\/2h26d2\/920113\/17122384954KJ00dAu\/Bildschirmfoto_2024_04_04_um_15.47.45.png","datePublished":"2024-04-30T14:02:58+00:00","dateModified":"2024-04-30T14:03:00+00:00","breadcrumb":{"@id":"https:\/\/www.wildix.com\/es\/email-news\/apr-12-2024-neuigkeiten-vom-qph-q2-2024\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.wildix.com\/es\/email-news\/apr-12-2024-neuigkeiten-vom-qph-q2-2024\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.wildix.com\/es\/email-news\/apr-12-2024-neuigkeiten-vom-qph-q2-2024\/#primaryimage","url":"https:\/\/go.pardot.com\/l\/920113\/2024-04-04\/2h26d2\/920113\/17122384954KJ00dAu\/Bildschirmfoto_2024_04_04_um_15.47.45.png","contentUrl":"https:\/\/go.pardot.com\/l\/920113\/2024-04-04\/2h26d2\/920113\/17122384954KJ00dAu\/Bildschirmfoto_2024_04_04_um_15.47.45.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.wildix.com\/es\/email-news\/apr-12-2024-neuigkeiten-vom-qph-q2-2024\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.wildix.com\/es\/"},{"@type":"ListItem","position":2,"name":"News on WMP","item":"https:\/\/www.wildix.com\/es\/email-news\/"},{"@type":"ListItem","position":3,"name":"Apr 12, 2024 \u2013 Neuigkeiten vom QPH Q2\/2024"}]},{"@type":"WebSite","@id":"https:\/\/www.wildix.com\/es\/#website","url":"https:\/\/www.wildix.com\/es\/","name":"Wildix","description":"","publisher":{"@id":"https:\/\/www.wildix.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.wildix.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.wildix.com\/es\/#organization","name":"Wildix","url":"https:\/\/www.wildix.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.wildix.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.wildix.com\/wp-content\/uploads\/2021\/09\/logo-1.svg","contentUrl":"https:\/\/www.wildix.com\/wp-content\/uploads\/2021\/09\/logo-1.svg","caption":"Wildix"},"image":{"@id":"https:\/\/www.wildix.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/groups\/wildixtechwizards\/?mibextid=6NoCDW","https:\/\/x.com\/wildix_"]}]}},"_links":{"self":[{"href":"https:\/\/www.wildix.com\/es\/wp-json\/wp\/v2\/email-news\/8085763","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.wildix.com\/es\/wp-json\/wp\/v2\/email-news"}],"about":[{"href":"https:\/\/www.wildix.com\/es\/wp-json\/wp\/v2\/types\/email-news"}],"author":[{"embeddable":true,"href":"https:\/\/www.wildix.com\/es\/wp-json\/wp\/v2\/users\/26"}],"wp:attachment":[{"href":"https:\/\/www.wildix.com\/es\/wp-json\/wp\/v2\/media?parent=8085763"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}