{"id":8048690,"date":"2023-08-21T08:00:00","date_gmt":"2023-08-21T06:00:00","guid":{"rendered":"https:\/\/www.wildix.com\/?post_type=email-news&#038;p=8048690"},"modified":"2023-09-06T00:45:37","modified_gmt":"2023-09-05T22:45:37","slug":"aug-21-2023-update-promo-zu-x-hoppers-sales-incentive-um-drei-monate-verlaengert","status":"publish","type":"email-news","link":"https:\/\/www.wildix.com\/es\/email-news\/aug-21-2023-update-promo-zu-x-hoppers-sales-incentive-um-drei-monate-verlaengert\/","title":{"rendered":"Aug 21, 2023 \u2013 Update: Promo zu x-hoppers Sales Incentive um drei Monate verl\u00e4ngert"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Anl\u00e4sslich des EMEA Partnertags verk\u00fcndigte Wildix den offiziellen Launch von x-hoppers, der <a href=\"https:\/\/www.x-hoppers.com\/de\" target=\"_blank\" rel=\"noreferrer noopener\">vertikalen L\u00f6sung f\u00fcr den Einzelhandel<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wir m\u00f6chten Sie nun dar\u00fcber informieren, dass die <strong>Promo zum x-hoppers Sales Incentive<\/strong> f\u00fcr alle Partner, die die entsprechenden Kriterien erf\u00fcllen, bis zum <strong>31. M\u00e4rz 2024 verl\u00e4ngert<\/strong> wurde.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Und so k\u00f6nnen Sie daran teilnehmen: <\/strong>Arbeiten Sie gemeinsam mit Ihrem Partner Account Manager von Wildix an potenziellen Interessenten f\u00fcr die x-hoppers L\u00f6sung. F\u00fchren Sie so viele Erstgespr\u00e4che mit potenziellen Kunden aus dem station\u00e4ren Handel wie m\u00f6glich. Beziehen Ihren Partner Account Manager gleich beim ersten Treffen mit ein und wir werden gemeinsam die Meetings durchf\u00fchren sowie bei der Vorstellung der L\u00f6sung unterst\u00fctzen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>NEU:<\/strong> Voraussetzung f\u00fcr die Teilnahme am x-hoppers Sales Incentive ist, dass Ihr Qualifizierungsgespr\u00e4ch bis zum 31. Dezember 2023 stattgefunden hat und die Demo f\u00fcr einen Termin vor dem 31. M\u00e4rz 2024 angesetzt ist.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Auf die drei besten Vertriebsmitarbeiter in Bezug auf die Anzahl der Opportunities, die in der Demo-Phase qualifiziert werden, warten am Ende des ersten Quartals 2024 folgende Preise:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>1. Platz: Apple Watch<\/li>\n\n\n\n<li>2. Platz: Airpods Pro<\/li>\n\n\n\n<li>3. Platz: Apple Homepod<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Sie m\u00f6chten mehr rund um die x-hoppers L\u00f6sung erfahren?<\/strong> Werfen Sie einen Blick auf die x-hoppers Website sowie den x-hoppers Admin Guide und die Wildix Partner Community Dokumentation: <a href=\"https:\/\/www.x-hoppers.com\/de\">www.x-hoppers.com\/de<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00dcbrigens, kennen Sie bereits die <strong>x-hoppers Magic Box<\/strong>? Die x-hoppers Box wurde von uns entwickelt, um Sie bei der Vorf\u00fchrung der x-hoppers L\u00f6sung zu unterst\u00fctzen, und ist f\u00fcr jeden qualifizierten Partner erh\u00e4ltlich. Um sich f\u00fcr eine x-hoppers Box zu qualifizieren, ben\u00f6tigen Sie entweder:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>einen DealRoom-Code von unserem Wildix Partner Day in Tallinn<\/li>\n\n\n\n<li>eine Opportunity f\u00fcr die x-hoppers L\u00f6sung, die von mir als Ihrem Partner Development Manager best\u00e4tigt wurde<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">In letztem Fall gehen Sie bitte wir folgt vor, um den Prozess zu verschlanken:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Sie sind bereits Mitglied der Salesforce Partner Community<\/li>\n\n\n\n<li>Kontaktieren Sie Ihren Partner Development Manager und teilen Sie diesem die Details zur Opportunity mit<\/li>\n\n\n\n<li>Wir pr\u00fcfen die Opportunity und vereinbaren einen Termin f\u00fcr eine Demo gemeinsam mit Ihnen und dem Endkunden<\/li>\n\n\n\n<li>Ihr Partner Development Manager wird in Ihrem Namen eine x-hoppers Box anfordern<\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">Falls Sie noch nicht Mitglied der Salesforce Partner Community sein sollten, dann sprechen Sie uns gerne an, um Zugang zu erhalten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lassen Sie uns gemeinsam mehr MRR aus der vertikalen L\u00f6sung von Wildix f\u00fcr den Einzelhandel gewinnen!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Anl\u00e4sslich des EMEA Partnertags verk\u00fcndigte Wildix den offiziellen Launch von x-hoppers, der vertikalen L\u00f6sung f\u00fcr den Einzelhandel. Wir m\u00f6chten Sie nun dar\u00fcber informieren, dass die Promo zum x-hoppers Sales Incentive f\u00fcr alle Partner, die die entsprechenden Kriterien erf\u00fcllen, bis zum 31. M\u00e4rz 2024 verl\u00e4ngert wurde. Und so k\u00f6nnen Sie daran teilnehmen: Arbeiten Sie gemeinsam mit [&hellip;]<\/p>\n","protected":false},"author":26,"featured_media":0,"parent":0,"template":"","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_jet_sm_ready_style":"","_jet_sm_style":"","_jet_sm_controls_values":"","_jet_sm_fonts_collection":"","_jet_sm_fonts_links":""},"class_list":["post-8048690","email-news","type-email-news","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aug 21, 2023 \u2013 Update: Promo zu x-hoppers Sales Incentive um drei Monate verl\u00e4ngert | Wildix<\/title>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aug 21, 2023 \u2013 Update: Promo zu x-hoppers Sales Incentive um drei Monate verl\u00e4ngert | Wildix\" \/>\n<meta property=\"og:description\" content=\"Anl\u00e4sslich des EMEA Partnertags verk\u00fcndigte Wildix den offiziellen Launch von x-hoppers, der vertikalen L\u00f6sung f\u00fcr den Einzelhandel. Wir m\u00f6chten Sie nun dar\u00fcber informieren, dass die Promo zum x-hoppers Sales Incentive f\u00fcr alle Partner, die die entsprechenden Kriterien erf\u00fcllen, bis zum 31. M\u00e4rz 2024 verl\u00e4ngert wurde. Und so k\u00f6nnen Sie daran teilnehmen: Arbeiten Sie gemeinsam mit [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.wildix.com\/es\/email-news\/aug-21-2023-update-promo-zu-x-hoppers-sales-incentive-um-drei-monate-verlaengert\/\" \/>\n<meta property=\"og:site_name\" content=\"Wildix\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/groups\/wildixtechwizards\/?mibextid=6NoCDW\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-05T22:45:37+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@wildix_\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aug 21, 2023 \u2013 Update: Promo zu x-hoppers Sales Incentive um drei Monate verl\u00e4ngert | Wildix","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"es_ES","og_type":"article","og_title":"Aug 21, 2023 \u2013 Update: Promo zu x-hoppers Sales Incentive um drei Monate verl\u00e4ngert | Wildix","og_description":"Anl\u00e4sslich des EMEA Partnertags verk\u00fcndigte Wildix den offiziellen Launch von x-hoppers, der vertikalen L\u00f6sung f\u00fcr den Einzelhandel. Wir m\u00f6chten Sie nun dar\u00fcber informieren, dass die Promo zum x-hoppers Sales Incentive f\u00fcr alle Partner, die die entsprechenden Kriterien erf\u00fcllen, bis zum 31. M\u00e4rz 2024 verl\u00e4ngert wurde. Und so k\u00f6nnen Sie daran teilnehmen: Arbeiten Sie gemeinsam mit [&hellip;]","og_url":"https:\/\/www.wildix.com\/es\/email-news\/aug-21-2023-update-promo-zu-x-hoppers-sales-incentive-um-drei-monate-verlaengert\/","og_site_name":"Wildix","article_publisher":"https:\/\/www.facebook.com\/groups\/wildixtechwizards\/?mibextid=6NoCDW","article_modified_time":"2023-09-05T22:45:37+00:00","twitter_card":"summary_large_image","twitter_site":"@wildix_","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.wildix.com\/es\/email-news\/aug-21-2023-update-promo-zu-x-hoppers-sales-incentive-um-drei-monate-verlaengert\/","url":"https:\/\/www.wildix.com\/es\/email-news\/aug-21-2023-update-promo-zu-x-hoppers-sales-incentive-um-drei-monate-verlaengert\/","name":"Aug 21, 2023 \u2013 Update: Promo zu x-hoppers Sales Incentive um drei Monate verl\u00e4ngert | Wildix","isPartOf":{"@id":"https:\/\/www.wildix.com\/es\/#website"},"datePublished":"2023-08-21T06:00:00+00:00","dateModified":"2023-09-05T22:45:37+00:00","breadcrumb":{"@id":"https:\/\/www.wildix.com\/es\/email-news\/aug-21-2023-update-promo-zu-x-hoppers-sales-incentive-um-drei-monate-verlaengert\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.wildix.com\/es\/email-news\/aug-21-2023-update-promo-zu-x-hoppers-sales-incentive-um-drei-monate-verlaengert\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.wildix.com\/es\/email-news\/aug-21-2023-update-promo-zu-x-hoppers-sales-incentive-um-drei-monate-verlaengert\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.wildix.com\/es\/"},{"@type":"ListItem","position":2,"name":"News on WMP","item":"https:\/\/www.wildix.com\/es\/email-news\/"},{"@type":"ListItem","position":3,"name":"Aug 21, 2023 \u2013 Update: Promo zu x-hoppers Sales Incentive um drei Monate verl\u00e4ngert"}]},{"@type":"WebSite","@id":"https:\/\/www.wildix.com\/es\/#website","url":"https:\/\/www.wildix.com\/es\/","name":"Wildix","description":"","publisher":{"@id":"https:\/\/www.wildix.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.wildix.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.wildix.com\/es\/#organization","name":"Wildix","url":"https:\/\/www.wildix.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.wildix.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.wildix.com\/wp-content\/uploads\/2021\/09\/logo-1.svg","contentUrl":"https:\/\/www.wildix.com\/wp-content\/uploads\/2021\/09\/logo-1.svg","caption":"Wildix"},"image":{"@id":"https:\/\/www.wildix.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/groups\/wildixtechwizards\/?mibextid=6NoCDW","https:\/\/x.com\/wildix_"]}]}},"_links":{"self":[{"href":"https:\/\/www.wildix.com\/es\/wp-json\/wp\/v2\/email-news\/8048690","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.wildix.com\/es\/wp-json\/wp\/v2\/email-news"}],"about":[{"href":"https:\/\/www.wildix.com\/es\/wp-json\/wp\/v2\/types\/email-news"}],"author":[{"embeddable":true,"href":"https:\/\/www.wildix.com\/es\/wp-json\/wp\/v2\/users\/26"}],"wp:attachment":[{"href":"https:\/\/www.wildix.com\/es\/wp-json\/wp\/v2\/media?parent=8048690"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}